{"id":8956,"date":"2023-05-17T00:55:10","date_gmt":"2023-05-17T00:55:10","guid":{"rendered":"https:\/\/www.lapoliticaonline.com\/politica\/la-corte-rechazo-la-recusacion-de-los-jueces-que-pidio-san-juan-por-la-suspension-de-las-elecciones\/"},"modified":"2023-05-17T00:55:10","modified_gmt":"2023-05-17T00:55:10","slug":"la-corte-rechazo-la-recusacion-de-los-jueces-que-pidio-san-juan-por-la-suspension-de-las-elecciones","status":"publish","type":"post","link":"https:\/\/latecordoba.com\/index.php\/2023\/05\/17\/la-corte-rechazo-la-recusacion-de-los-jueces-que-pidio-san-juan-por-la-suspension-de-las-elecciones\/","title":{"rendered":"La Corte rechaz\u00f3 la recusaci\u00f3n de los jueces que pidi\u00f3 San Juan por la suspensi\u00f3n de las elecciones"},"content":{"rendered":"\n<div><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/05\/la-corte-rechazo-la-recusacion-de-los-jueces-que-pidio-san-juan-por-la-suspension-de-las-elecciones.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<div id=\"vsmcontent\" readability=\"84\">\n<p>&nbsp;<span>La Corte Suprema desestim\u00f3 el pedido de excusaci\u00f3n y rechaz\u00f3 las recusaciones planteadas por la provincia de San Juan en el caso en que se cuestiona una nueva candidatura del gobernador, Sergio U\u00f1ac.<\/span><\/p>\n<p>El pr\u00f3ximo paso es que la Corte env\u00ede el expediente con el informe presentado por la provincia de San Juan a Procuraci\u00f3n para que se resuelva la cuesti\u00f3n de fondo.<\/p>\n<p>La provincia de San Juan hizo una presentaci\u00f3n solicitando que los integrantes de la Corte que firmaron el fallo mediante el cual se dict\u00f3 una medida cautelar que orden\u00f3 suspender las elecciones convocadas para el pasado domingo en las categor\u00edas de gobernador y vicegobernador se excusen de seguir entendiendo en la causa.<\/p>\n<p>En su presentaci\u00f3n el fiscal de Estado sanjuanino, Jorge Alvo, plante\u00f3 la recusaci\u00f3n de los ministros en caso de que no se excusen porque -a su entender- al momento de dictar la medida cautelar los jueces hab\u00edan adelantado su opini\u00f3n. Por otra parte, la provincia de San Juan present\u00f3 el informe solicitado por el m\u00e1ximo tribunal y pidi\u00f3 que se rechace la acci\u00f3n de amparo promovida en su contra.<\/p>\n<p>Ahora, sobre el pedido para que los magistrados se excusen, los ministros del m\u00e1ximo tribunal consideraron que resulta inadmisible porque la facultad de excusaci\u00f3n de los jueces de la Corte, mediando causa legal de recusaci\u00f3n o no, es ajena a la actividad procesal de las partes.<\/p>\n<figure class=\"vsmwidget widget-type-iframe\" vsmtype=\"iframe\" contenteditable=\"false\"><\/figure>\n<\/div>\n<p><strong>Copyright La Politica Online SA 2023.<\/strong><br \/>Por favor no corte ni pegue en la web nuestras notas, tiene la posibilidad de redistribuirlas usando nuestras herramientas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> El M\u00e1ximo Tribunal rechaz\u00f3 el pedido del gobierno de U\u00f1ac y le pidi\u00f3 a la Procuraci\u00f3n que resuelva la cuesti\u00f3n de fondo.  <\/p>\n","protected":false},"author":1,"featured_media":8957,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/8956"}],"collection":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/comments?post=8956"}],"version-history":[{"count":0,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/8956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media\/8957"}],"wp:attachment":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media?parent=8956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/categories?post=8956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/tags?post=8956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}