{"id":8940,"date":"2023-05-16T14:00:00","date_gmt":"2023-05-16T14:00:00","guid":{"rendered":"https:\/\/www.iprofesional.com\/finanzas\/381907-dolar-blue-rumbo-a-los-500-pese-a-la-suba-de-tasas"},"modified":"2023-05-16T14:00:00","modified_gmt":"2023-05-16T14:00:00","slug":"dolar-blue-la-cotizacion-va-rumbo-a-los-500-pese-a-la-suba-de-las-tasas","status":"publish","type":"post","link":"https:\/\/latecordoba.com\/index.php\/2023\/05\/16\/dolar-blue-la-cotizacion-va-rumbo-a-los-500-pese-a-la-suba-de-las-tasas\/","title":{"rendered":"D\u00f3lar blue: \u00bfla cotizaci\u00f3n va rumbo a los $500 pese a la suba de las tasas?"},"content":{"rendered":"\n<div class=\"media_block\"><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/05\/dolar-blue-la-cotizacion-va-rumbo-a-los-500-pese-a-la-suba-de-las-tasas.jpg\"><\/div>\n<p><span>El <a href=\"https:\/\/www.iprofesional.com\/finanzas\/381850-dolar-blue-hoy-la-cotizacion-del-15-de-mayo-de-2023\" target=\"_blank\" rel=\"noopener\">d\u00f3lar blue<\/a> registr\u00f3 este lunes 15 de mayo un salto de $9 <\/span>al cerrar en<strong> $483,<\/strong> pese a la suba de la tasa de inter\u00e9s de pol\u00edtica monetaria y del rendimiento de los plazos fijo a 97% anual y otras medidas anunciadas durante el fin de semana por el ministerio de Econom\u00eda. Y para algunos analistas,<span> el d\u00f3lar informal podr\u00eda coquetear otra vez con tocar los $500 hacia fin de mes.<\/span>\n<\/p>\n<p>Para los economistas consultados por iProfesional, la escalada del d\u00f3lar informal es una reacci\u00f3n al mal dato de inflaci\u00f3n de abril de 8,4%, superior a lo que preve\u00eda el mercado, y a que<span> la suba de la tasa de inter\u00e9s se queda corta frente a las expectativas inflacionarias <\/span>para mayo por lo cual resulta insuficiente para desalentar la dolarizaci\u00f3n en un contexto de incertidumbre electoral.\n<\/p>\n<p>Para el mercado, las medidas anunciadas por Econom\u00eda &#8220;<strong>son parches desesperados<\/strong>&#8221; que no revierten el deterioro de las expectativas al no solucionar el problema de fondo que es la escasez de reservas.\n<\/p>\n<p>Adem\u00e1s, los analistas consideran que las nuevas restricciones para importadores para operar con los d\u00f3lares financieros &#8211; CCL y MEP- que puso en marcha el viernes el BCRA, junto con una resoluci\u00f3n de la Comisi\u00f3n Nacional de Valores tambi\u00e9n conocida el viernes, con restricciones para los Fondos Comunes de Inversi\u00f3n de suscribir, contribuyen a recalentar el blue.\n<\/p>\n<p>En este contexto, en el mercado ven chances de que el d\u00f3lar blue durante la segunda quincena de este mes pueda volver a testear los $500 millones, un valor que amag\u00f3 con tocar durante la corrida cambiaria de la \u00faltima semana de abril.\n<\/p>\n<h2>D\u00f3lar blue: \u00bfpor qu\u00e9 se dispar\u00f3?<\/h2>\n<p>La economista<strong> Natalia Motyl <\/strong>evalu\u00f3 que &#8220;la suba del d\u00f3lar blue responde tanto a los datos de <a href=\"https:\/\/www.iprofesional.com\/economia\/381781-alerta-por-los-precios-esta-fue-la-inflacion-de-abril-2023\" target=\"_blank\" rel=\"noopener\">inflaci\u00f3n de abril<\/a> conocido el viernes como a las medidas tomadas por el Gobierno&#8221;, dado que &#8220;hoy el mercado ha descontado que <span>la suba de tasas de inter\u00e9s en 600 puntos b\u00e1sicos ha sido insuficiente&#8221;.<\/span>\n<\/p>\n<div class=\"imagen\" readability=\"7\"><img decoding=\"async\" loading=\"lazy\" class=\"lazyload\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/05\/dolar-blue-la-cotizacion-va-rumbo-a-los-500-pese-a-la-suba-de-las-tasas-1.jpg\" alt=\"El d\u00f3lar blue arranc\u00f3 la semana con un salto de $9 al cerrar en $483\" width=\"880\" height=\"495\"><\/p>\n<p>El d\u00f3lar blue arranc\u00f3 la semana con un salto de $9 al cerrar en $483<\/p>\n<\/div>\n<p>&#8220;La tasa efectiva mensual (TEA) qued\u00f3 por debajo de la inflaci\u00f3n, y la esperada de mayo, y los instrumentos en pesos han dejado de ser atractivos para el ahorrista en un contexto en el que se espera una correcci\u00f3n del mercado cambiario post elecciones&#8221;, afirm\u00f3.\n<\/p>\n<p>Asimismo, la economista sostuvo que <span>&#8220;las dificultades para acumular reservas por parte del BCRA no hace m\u00e1s que presionar la demanda de d\u00f3lares por cobertura,<\/span> hoy las reservas netas est\u00e1n en rojo en u$s3.300 millones y siguen cayendo, eso agudiza la crisis de confianza que impacta negativamente sobre la demanda del peso&#8221;.\n<\/p>\n<p>En sinton\u00eda, <strong>Andr\u00e9s Reschini<\/strong>, analista de F2 Soluciones Financieras, vincul\u00f3 la escalada del d\u00f3lar blue a que &#8220;<span>los anuncios del fin de semana en general dan la idea de que no se quiere combatir en serio a los problemas<\/span> y se buscan atajos para llegar a fin de mandato aunque se profundicen los desequilibrios&#8221;.\n<\/p>\n<p>De igual visi\u00f3n, el economista<strong> Federico Glustein <\/strong>atribuy\u00f3 el salto del blue a una reacci\u00f3n al &#8220;dato de inflaci\u00f3n de 8,4%, superior al mes anterior, que hace derivar un n\u00famero de medidas que son parches, pero que afectan a la obtenci\u00f3n de d\u00f3lares financieros por un lado y que muestra una eventual erogaci\u00f3n de d\u00f3lares en importados para conseguir alimentos m\u00e1s baratos&#8221;.\n<\/p>\n<p>&#8220;<span>Se ve que no hay un plan de reducci\u00f3n del gasto fiscal, por ende, las medidas son de s\u00e1bana corta, no atacan los problemas, y mayormente, dificultan el escenario&#8221;<\/span>, critic\u00f3.\n<\/p>\n<p>A su vez, el analista financiero<strong> Christian Buteler<\/strong> dijo que &#8220;cuando empieza a desaparecer el pure de principio de mes, <span>cuesta conseguir vendedores y el mercado est\u00e1 muy chico<\/span>, entonces se reduce la oferta, y por m\u00e1s que no suba la demanda, termina tirando el precio para arriba&#8221;.\n<\/p>\n<div class=\"imagen\" readability=\"9\"><img decoding=\"async\" loading=\"lazy\" class=\"lazyload\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/05\/dolar-blue-la-cotizacion-va-rumbo-a-los-500-pese-a-la-suba-de-las-tasas-2.jpg\" alt=\"Para los analistas, el salto del blue es una reacci\u00f3n al mal dato de inflaci\u00f3n de abril\" width=\"880\" height=\"495\"><\/p>\n<p>Para los analistas, el salto del blue es una reacci\u00f3n al mal dato de inflaci\u00f3n de abril de 8,4%&nbsp;<\/p>\n<\/div>\n<h2>Suba de tasas: \u00bfdesalentar\u00e1 dolarizaci\u00f3n y volver\u00e1 el carry trade?<\/h2>\n<p><strong>Buteler <\/strong>remarc\u00f3 que &#8220;<a href=\"https:\/\/www.iprofesional.com\/finanzas\/381830-el-plazo-fijo-paga-mas-desde-el-lunes-cuanto-ganas-con-100000\" target=\"_blank\" rel=\"noopener\">la suba de la tasa de inter\u00e9s<\/a> que dar\u00e1 un rendimiento mensual de 7,97%termina quedando negativa en cuanto a la inflaci\u00f3n de abril y la esperada para este mes que muchos estiman que empieza otra vez con un 8 adelante, pero adem\u00e1s el problema es la emisi\u00f3n de pesos, y ese es el primer factor de inestabilidad del tipo de cambio&#8221;.\n<\/p>\n<p><span>&#8220;Mientras mantengas la emisi\u00f3n de pesos no hay tasa que alcance porque no hay demanda de dinero,<\/span> entonces los pesos que tiras a la calle, parte termina presionando al tipo de cambio porque se pasan a d\u00f3lares&#8221;, vaticin\u00f3.\n<\/p>\n<p>De igual diagn\u00f3stico, <strong>Jerem\u00edas Morlandi<\/strong>, director de pol\u00edticas p\u00fablicas del Centro de Estudios Econ\u00f3micos Argentina XXI (CEEAXXI) aleg\u00f3 que &#8220;podemos discutir sobre si subir la tasa es la medida correcta o no, pero lo cierto es que <span>continuar subiendola por debajo de la inflaci\u00f3n es una medida que s\u00f3lo a\u00f1ade ruido<\/span> y no aporta nada&#8221;.\n<\/p>\n<p>&#8220;En este contexto pol\u00edtico y econ\u00f3mico se necesitan medidas mucho m\u00e1s robustas que una tibia suba de tasa para revivir la demanda de dinero, dado que si est\u00e1 contin\u00faa cayendo no hay suba de tasa que la recomponga&#8221;, objet\u00f3.\n<\/p>\n<p>Agreg\u00f3 que<span> &#8220;subir la tasa incrementa la velocidad a la que crecen los pasivos del BCRA, que ya superan los $12,5 billones, a esta nueva tasa deber\u00e1 emitir $1 bill\u00f3n por mes <\/span>s\u00f3lo para solventar los intereses,y al generar la expectativa de m\u00e1s emisi\u00f3n, se incrementan las expectativas de inflaci\u00f3n futura&#8221;\n<\/p>\n<p>Por su parte, <strong>Motyl<\/strong> cuestion\u00f3 que <span>&#8220;no hay grandes anuncios que ataquen el problema de fondo que es el exceso de papelitos de colores (pesos),<\/span> son parches desesperados para ver si logran aguantar un poco m\u00e1s&#8221; y eso &#8220;es una se\u00f1al negativa a los mercados&#8221; , por lo que prev\u00e9 &#8220;una nueva dolarizaci\u00f3n de carteras&#8221;.\n<\/p>\n<div class=\"imagen\" readability=\"9\"><img decoding=\"async\" loading=\"lazy\" class=\"lazyload\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/05\/dolar-blue-la-cotizacion-va-rumbo-a-los-500-pese-a-la-suba-de-las-tasas-3.jpg\" alt=\"Para los analistas, la nueva suba de tasas del plazo fijo se qued\u00f3 corta y no frenar\u00e1 dolarizaci\u00f3n\" width=\"880\" height=\"495\"><\/p>\n<p>Para los analistas, la nueva suba de tasas del plazo fijo se qued\u00f3 corta frente a inflaci\u00f3n y no frenar\u00e1 dolarizaci\u00f3n<\/p>\n<\/div>\n<p><strong>Reschini<\/strong> coincidi\u00f3 que &#8220;las medidas son un refuerzo al \u2018Plan lLegar\u2019, y no constituyen soluci\u00f3n alguna a los problemas de fondo: son como acelerar y frenar a la vez, puesto que desincentivan inversi\u00f3n con suba de tasas y a la vez incentivan el consumo y expanden a trav\u00e9s de los enormes pasivos remunerados del BCRA, lo que empeorar\u00e1 la inflaci\u00f3n&#8221;.\n<\/p>\n<p>En ese marco, el experto advirti\u00f3 que &#8220;la tasa sigue qued\u00e1ndose corta&#8221; por lo cual opin\u00f3 que &#8220;<span>apuestas por carry trade con este desborde inflacionario y una tasa que sigue por detr\u00e1s, con un BCRA sin reservas, lo veo demasiado arriesgado&#8221;.<\/span>\n<\/p>\n<p>Para <strong>Glustein<\/strong>, &#8220;la suba de las tasas es fuerte, pensando que hace d\u00edas la subieron 10 puntos porcentuales, pero la realidad es que es probable que no sirva, dado que<strong> la dolarizaci\u00f3n pre electoral no tiene freno&#8221;<\/strong>. Y a\u00f1adi\u00f3 que &#8220;no cambia la sustancia del contexto actual, la demanda de d\u00f3lares es notoria y creciente, a medida que se acerca el escenario electoral&#8221;.\n<\/p>\n<p>Asimismo, <strong>Fernando Baer<\/strong>, economista jefe de Quantum Finanzas, afirm\u00f3 que la suba de tasa &#8220;no es suficiente dada la nominalidad (inflaci\u00f3n)&#8221; para mantener calmos a los d\u00f3lares paralelos, juzg\u00f3 que &#8220;no es una buena medida aumentar la intervenci\u00f3n (en el mercado de cambios) &#8221; y augur\u00f3 que &#8220;las tensiones cambiarias seguir\u00e1n si el desequilibrio monetario sigue expandi\u00e9ndose&#8221;. En este contexto, el experto dijo que &#8220;<span>no creo que con estos niveles de tasa aparezcan apuestas de carry trade&#8221;.<\/span>\n<\/p>\n<h2>D\u00f3lar blue: \u00bfrumbo a los $500?<\/h2>\n<p>El d\u00f3lar blue el martes 25 de abril, en plena corrida cambiaria, cerr\u00f3 en un valor r\u00e9cord de $495, aunque en esa jornada lleg\u00f3 a tocar un pico de $497.Pese a la nueva suba de la tasa, los analistas advierten que el d\u00f3lar blue podr\u00eda retomar la escalada rumbo a los $500 durante la segunda quincena de mayo en un contexto de mayores restricciones al CCL y MEP, exceso de pesos, escasez de d\u00f3lares, e incertidumbre electoral.\n<\/p>\n<p>Para <strong>Reschini<\/strong>, &#8220;pueden llegar a contener un desborde cambiario por un tiempo con esta sua de tasa, mayores restricciones e intervenciones, pero sin duda la tendencia seguir\u00e1 al alza&#8221;, por lo que cree que &#8220;<span>no ser\u00eda nada descabellado en un contexto de inestabilidad creciente&#8221; que el d\u00f3lar blue amague con los $500.<\/span>\n<\/p>\n<div class=\"imagen\" readability=\"9\"><img decoding=\"async\" loading=\"lazy\" class=\"lazyload\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/05\/dolar-blue-la-cotizacion-va-rumbo-a-los-500-pese-a-la-suba-de-las-tasas-4.jpg\" alt=\"Para analistas, las medidas anunciadas el fin de semana no solucionan el problema de fondo que es la escasez de reservas\" width=\"880\" height=\"495\"><\/p>\n<p>Para analistas, las medidas anunciadas el fin de semana no solucionan el problema de fondo que es la escasez de reservas<\/p>\n<\/div>\n<p>Para <strong>Motyl,<\/strong>&nbsp; hay una serie de factores que presionan a los d\u00f3lares paralelos: &#8220;el dato de inflaci\u00f3n que impulsa una mayor demanda de d\u00f3lares; la ca\u00edda de reservas internacionales; la demora en la aprobaci\u00f3n del FMI de los desembolsos, la aceleraci\u00f3n econ\u00f3mica de principales socios comerciales&#8221;.&nbsp;&nbsp;\n<\/p>\n<p>&#8220;<span>Todo anticipa menos d\u00f3lares para el futuro lo que presiona a\u00fan m\u00e1s la demanda de d\u00f3lares ante una inevitable correcci\u00f3n<\/span>&#8220;, aleg\u00f3. En ese marco, la economista vislumbra <span>&#8220;<\/span><strong>un dolar blue a $500 para fin de este mes&#8221;<\/strong>\n<\/p>\n<p>Por su parte, el analista financiero<strong> Gustavo Ber<\/strong> argument\u00f3 que la nueva suba en la tasa de inter\u00e9s &#8220;no resultar\u00eda efectiva en el actual delicado contexto para resolver el exceso de pesos y la escasez de d\u00f3lares, ni siquiera a modo de \u2018puente\u2019 mientras se esperan que las negociaciones con el FMI aporten fondos frescos, toda vez que con el d\u00f3lar agro\u00a8no se retienen divisas&#8221;.\n<\/p>\n<p>&#8220;Aunque arrancaron relativamente tranquilos, con el correr de la rueda,<span> los d\u00f3lares financieros desregulados y el libre (blue) se fueron reacomodando al alza como respuesta a <a href=\"https:\/\/www.iprofesional.com\/economia\/381825-plazos-fijos-tarjetas-y-dolar-las-nuevas-medidas-de-massa\" target=\"_blank\" rel=\"noopener\">las \u00faltimas medidas econ\u00f3micas anunciadas<\/a> ya que los operadores anticipan resultar\u00e1n poco efectivas para mejorar las expectativas en el actual contexto pol\u00edtico-econ\u00f3mico&#8221;,<\/span> se\u00f1al\u00f3.\n<\/p>\n<p>Ber advirti\u00f3 que &#8220;la nueva suba en la tasa tendr\u00eda implicancias negativas en la actividad econ\u00f3mica y tambi\u00e9n sobre la din\u00e1mica de los intereses de los pasivos remunerados del BCRA, lo cual presiona adem\u00e1s incluso m\u00e1s a la din\u00e1mica de la inflaci\u00f3n&#8221;.&nbsp;\n<\/p>\n<p>&#8220;A medida que crece el clima de incertidumbre, la tasa resulta una herramienta menos efectiva para mejorar las expectativas de los agentes econ\u00f3micos y as\u00ed frenar la b\u00fasqueda de cobertura, por lo cual<span> la aceleraci\u00f3n de la nominalidad de la econom\u00eda invita a testear los $ 500 en las pr\u00f3ximas semanas&#8221;<\/span>, especul\u00f3.\n<\/p>\n<div class=\"imagen\" readability=\"7\"><img decoding=\"async\" loading=\"lazy\" class=\"lazyload\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/05\/dolar-blue-la-cotizacion-va-rumbo-a-los-500-pese-a-la-suba-de-las-tasas-5.jpg\" alt=\"Algunos analistas ven chances de que el d\u00f3lar blue para fin de mes pueda tocar $500\" width=\"880\" height=\"495\"><\/p>\n<p>Algunos analistas ven chances de que el d\u00f3lar blue para fin de mes pueda tocar $500<\/p>\n<\/div>\n<p><strong>Glustein<\/strong> tambi\u00e9n asegur\u00f3 que el valor del d\u00f3lar blue &#8220;tiene para crecer un trayecto&#8221; aunque consider\u00f3 que &#8220;<span>todav\u00eda es muy temprano para que alcance los $500&#8243;,<\/span> y prev\u00e9 que ese valor<strong> podria alcanzarse reci\u00e9n &#8220;cerca del cobro del aguinaldo&#8221;.<\/strong>\n<\/p>\n<div class=\"tepuedeinteresar\">\n<p>Te puede interesar<\/p>\n<\/p><\/div>\n<p>Seg\u00fan su visi\u00f3n, el blue subir\u00e1 un &#8220;d\u00eda o dos m\u00e1s, y despu\u00e9s se estabiliza porque se hace rulo con el MEP y aumenta la oferta, baja el precio, y vuelve a un escenario de relativa calma&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"\n<div class=\"media_block\"><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/05\/dolar-blue-la-cotizacion-va-rumbo-a-los-500-pese-a-la-suba-de-las-tasas.jpg\"><\/div>\n<p> Ante una suba de tasas que se queda corta frente a inflaci\u00f3n y mayores restricciones a los d\u00f3lares financieros, \u00bfqu\u00e9 anticipan los expertos del mercado? <iframe width=\"0\" height=\"0\" border=\"0\"> <script> (function(i,s,o,g,r,a,m){i['GoogleAnalyticsObject']=r;i[r]=i[r]||function(){ (i[r].q=i[r].q||[]).push(arguments)},i[r].l=1*new Date();a=s.createElement(o), m=s.getElementsByTagName(o)[0];a.async=1;a.src=g;m.parentNode.insertBefore(a,m) })(window,document,'script','https:\/\/www.google-analytics.com\/analytics.js','ga'); ga('create', 'GTM-5LW5KQD', 'auto'); ga('require', 'displayfeatures'); ga('set', 'campaignSource', 'RSS Client for iProfesional'); ga('set', 'campaignMedium', 'RSS Client for iProfesional'); ga('set', {\"dataSource\": \"rss.atom.iprofesional.com\"}); ga('set', {\"referrer\": \"rss.atom.iprofesional.com\"}); ga('set', 'title', 'RSS Client for iProfesional'); ga('send', 'pageview'); <\/script> <!-- Begin comScore Tag --> <script>\nvar _comscore = _comscore || [];\n_comscore.push({ c1: \"2\", c2: \"16597048\" });\n(function() {\nvar s = document.createElement(\"script\"), el = document.getElementsByTagName(\"script\")[0]; s.async = true;\ns.src = \"https:\/\/sb.scorecardresearch.com\/cs\/16597048\/beacon.js\";\nel.parentNode.insertBefore(s, el);\n})(); <\/script> <noscript> <img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/05\/dolar-blue-la-cotizacion-va-rumbo-a-los-500-pese-a-la-suba-de-las-tasas.gif\"> <\/noscript> <!-- End comScore Tag --> <\/iframe>  <\/p>\n","protected":false},"author":1,"featured_media":8941,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/8940"}],"collection":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/comments?post=8940"}],"version-history":[{"count":0,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/8940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media\/8941"}],"wp:attachment":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media?parent=8940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/categories?post=8940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/tags?post=8940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}