{"id":8932,"date":"2023-05-16T13:14:00","date_gmt":"2023-05-16T13:14:00","guid":{"rendered":"https:\/\/www.puntal.com.ar\/premios-gardel\/trueno-y-dante-spinetta-los-principales-candidatos-los-premios-gardel-2023-n190990"},"modified":"2023-05-16T13:14:00","modified_gmt":"2023-05-16T13:14:00","slug":"trueno-y-dante-spinetta-los-principales-candidatos-de-los-premios-gardel-2023","status":"publish","type":"post","link":"https:\/\/latecordoba.com\/index.php\/2023\/05\/16\/trueno-y-dante-spinetta-los-principales-candidatos-de-los-premios-gardel-2023\/","title":{"rendered":"Trueno y Dante Spinetta, los principales candidatos de los Premios Gardel 2023"},"content":{"rendered":"\n<div><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/05\/trueno-y-dante-spinetta-los-principales-candidatos-de-los-premios-gardel-2023.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p> Adem\u00e1s de Trueno por &#8220;Bien o mal&#8221; y Spinetta por &#8220;Mesa dulce&#8221;, los competidores por el \u00c1lbum del A\u00f1o que consagra al ganador del Gardel de Oro, que el a\u00f1o pasado alz\u00f3 Wos, son Bab\u00e1s\u00f3nicos por &#8220;Trinchera&#8221;, Mar\u00eda Becerra por &#8220;La nena de Argentina&#8221;, y Ciro y Los Persas por &#8220;Sue\u00f1os (Un viaje en el tiempo)&#8221; registrado junto a la Orquesta Filarm\u00f3nica de Mendoza.<\/p>\n<p>Entre los artistas con participaciones en m\u00e1s categor\u00edas tambi\u00e9n figuran Babas\u00f3nicos con seis; Mar\u00eda Becerra y Tini con cinco; Los Aut\u00e9nticos Decadentes, Bizarrap, Fito P\u00e1ez, Ciro y Luciano Pereyra con cuatro; y Nathy Peluso, La Konga, Eruca Sativa y Leo Genovese, con tres.<\/p>\n<p>Entre las 48 categor\u00edas que ser\u00e1n premiadas destaca tambi\u00e9n la de Canci\u00f3n del A\u00f1o, en la que pugnar\u00e1n por el premio &#8220;Quevedo: BZRP Music Sessions, Vol. 52&#8221;, de Bizarrap y Quevedo; &#8220;Bye Bye&#8221;, de Babas\u00f3nicos; &#8220;Bien o mal&#8221;, de Trueno, quien tambi\u00e9n se anota con &#8220;Argentina&#8221;, que lo uni\u00f3 con Nathy Peluso; &#8220;Fiesta Time&#8221;, de Leo Genovese; &#8220;La Triple t&#8221;, de Tini; &#8220;Una mujer como t\u00fa&#8221;, de Luciano Pereyra y Los \u00c1ngeles Azules; &#8220;Mi fiesta&#8221;, de Bandalos Chinos; la mundialista &#8220;Muchachos, ahora nos volvimos a ilusionar&#8221;, de la Mosca; y &#8220;Todos nos vamos a morir igual&#8221;, de Los Tekis y Los Aut\u00e9nticos Decadentes.<\/p>\n<p>Tambi\u00e9n se entregar\u00e1n menciones especiales a los ingenieros de sonido Am\u00edlcar Gilabert y Mario Breuer por su vasta trayectoria y destacada labor en la producci\u00f3n fonogr\u00e1fica.<\/p>\n<p>Tal como ocurre desde 2020, estos premios que cumplen 25 a\u00f1os no distinguen ganadores por g\u00e9nero e incluyen diversas categor\u00edas que contemplan una amplia gama de estilos musicales y distintos momentos de los procesos de producci\u00f3n.<\/p>\n<p><strong>En vivo<\/strong><\/p>\n<p>En tanto, la ceremonia contar\u00e1 con actuaciones de Mar\u00eda Becerra, Los Fabulosos Cadillacs, Trueno, Rei, Callejero Fino, L-Gante, Peipper, DJ Tao, La Joaqui, Le\u00f3n Gieco, V\u00edctor Heredia, Amelita Baltar, Ra\u00fal Lavi\u00e9, Yami Safdie y .<\/p>\n<p>&#8220;Esta es sin dudas una edici\u00f3n hist\u00f3rica de los Premios Gardel porque cumplen nada menos que 25 a\u00f1os celebrando la m\u00fasica argentina. Llegar hasta ac\u00e1 habi\u00e9ndose consolidado como el premio m\u00e1s importante de la m\u00fasica en nuestro pa\u00eds es ante todo un privilegio, significa una gran alegr\u00eda y tambi\u00e9n representa un enorme compromiso con nuestros artistas&#8221;, manifest\u00f3 Diego Zapico, presidente de la C\u00e1mara Argentina de Productores de Fonogramas y Videogramas (CAPIF), organizadora de los premios, a trav\u00e9s de un comunicado.<\/p>\n<p>Tambi\u00e9n destac\u00f3: &#8220;Por segundo a\u00f1o consecutivo los Premios se ver\u00e1n por la pantalla de Star+. Renovamos esta alianza que en 2022 tuvo un gran alcance de audiencia y buscamos ir por m\u00e1s junto con una plataforma que est\u00e1 cada d\u00eda m\u00e1s consolidada en la transmisi\u00f3n de eventos en vivo, con especial foco e inter\u00e9s en la m\u00fasica&#8221;<\/p>\n<p>La primera edici\u00f3n de los Premios Gardel se llev\u00f3 a cabo en 1999 y consagr\u00f3 con el m\u00e1ximo galard\u00f3n a Sandro. La de este martes, que tendr\u00e1 lugar en el Movistar Arena -en el barrio porte\u00f1o de Villa Crespo-, tendr\u00e1 transmisi\u00f3n en directo desde las 20 por Star +.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\nLos m\u00fasicos, que participan en nueve y siete nominaciones respectivamente, compiten por el &#8220;\u00c1lbum del A\u00f1o&#8221; (que consagra al ganador del Gardel de Oro) por sus obras &#8220;Bien o Mal&#8221;, del trapero de la Boca y &#8220;Mesa dulce&#8221;, del cantante y compositor.  <\/p>\n","protected":false},"author":1,"featured_media":8933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/8932"}],"collection":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/comments?post=8932"}],"version-history":[{"count":0,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/8932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media\/8933"}],"wp:attachment":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media?parent=8932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/categories?post=8932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/tags?post=8932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}