{"id":7463,"date":"2023-03-14T13:28:00","date_gmt":"2023-03-14T13:28:00","guid":{"rendered":"http:\/\/Article%20354105%20reposted%20in%20Econom\u00eda"},"modified":"2023-03-14T13:28:00","modified_gmt":"2023-03-14T13:28:00","slug":"como-saber-si-estoy-inhabilitado-para-comprar-dolares","status":"publish","type":"post","link":"https:\/\/latecordoba.com\/index.php\/2023\/03\/14\/como-saber-si-estoy-inhabilitado-para-comprar-dolares\/","title":{"rendered":"C\u00f3mo saber si estoy inhabilitado para comprar d\u00f3lares"},"content":{"rendered":"\n<div class=\"media_block\"><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/04\/como-saber-si-estoy-inhabilitado-para-comprar-dolares.jpg\"><\/div>\n<p><span>El <strong>BCRA<\/strong> tiene una serie de estrictas <strong>restricciones<\/strong> para la compra del d\u00f3lar ahorro en<a href=\"https:\/\/www.iprofesional.com\/finanzas\/376630-dolar-ahorro-por-esto-vuelven-a-crecer-las-compras-en-los-bancos\" target=\"_blank\" rel=\"noopener\"> <strong>b\u00fasqueda de aumentar las reservas del pa\u00eds.<\/strong><\/a> Los ahorristas argentinos cada vez tienen m\u00e1s dificultades para acceder a la divisa estadounidense.<\/span>\n<\/p>\n<p><span>El <strong>primer d\u00eda h\u00e1bil de cada mes<\/strong> se abre un <strong>nuevo per\u00edodo <\/strong>para la <strong>compra del cupo personal de u$s200 ahorro. <\/strong>La <strong>lista de vetados <\/strong>que no puede comprar d\u00f3lares <strong>crece cada d\u00eda<\/strong>, tomando a los que ya hab\u00edan sido exclu\u00eddos por otras restricciones.<\/span>\n<\/p>\n<div class=\"imagen\">\n<div class=\"imagen\">\n<div class=\"imagen\" readability=\"6\">\n<div class=\"imagen\" readability=\"7\"><img decoding=\"async\" loading=\"lazy\" class=\"lazyload\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/04\/como-saber-si-estoy-inhabilitado-para-comprar-dolares-1.jpg\" alt=\"La pregunta de todos los meses: qui\u00e9nes no pueden comprar d\u00f3lares\" width=\"941.6\" height=\"558.825\"><\/p>\n<p>La pregunta de todos los meses: qui\u00e9nes no pueden comprar d\u00f3lares<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h2><span><strong>Comprar d\u00f3lares: <\/strong><\/span>\u00bfc\u00f3mo saber si estoy habilitado?<\/h2>\n<p>La <strong>ANSES <\/strong>puso a disposici\u00f3n del p\u00fablico una base de datos con la que se puede controlar si uno est\u00e1 autorizado o inhabilitado para comprar d\u00f3lares.\n<\/p>\n<p>El sitio se encuentra en la p\u00e1gina de Anses y, <strong>para saber qui\u00e9nes no pueden comprar d\u00f3lares<\/strong>, se opera de la siguiente manera:\n<\/p>\n<div class=\"imagen\" readability=\"8\"><img decoding=\"async\" loading=\"lazy\" class=\"lazyload\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/04\/como-saber-si-estoy-inhabilitado-para-comprar-dolares-2.jpg\" alt=\"Los campos para ingresar n\u00famero de CUIL o CUIT dentro de Mi Anses.\" width=\"839\" height=\"276\"><\/p>\n<p>Qui\u00e9nes no pueden comprar d\u00f3lares: los campos para ingresar n\u00famero de CUIL o CUIT dentro de Mi Anses<\/p>\n<\/div>\n<p>Una vez ingresados los datos, el sistema de Anses indicar\u00e1 si es posible acceder o si se est\u00e1 inhabilitado para comprar d\u00f3lares. El mensaje &#8220;<strong>Denegatoria Certificaci\u00f3n Negativa<\/strong>&#8221; indica que la persona s\u00ed est\u00e1 habilitada a comprar divisas estadounidenses. A continuaci\u00f3n se muestra un ejemplo:\n<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"lazyload\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/04\/como-saber-si-estoy-inhabilitado-para-comprar-dolares-3.jpg\" alt width=\"880\" height=\"420\">\n<\/p>\n<p>&#8220;Denegatoria de Certificaci\u00f3n Negativa&#8221;: qui\u00e9nes pueden comprar d\u00f3lares<\/p>\n<h2>Qui\u00e9nes no pueden comprar d\u00f3lares por estar inhabilitados<\/h2>\n<p>Hay una larga lista de ahorristas que no pueden comprar d\u00f3lares. A continuaci\u00f3n, cu\u00e1les son los grupos que fueron excluidos del mercado cambiario:&nbsp;\n<\/p>\n<h3><strong>1.&nbsp;<\/strong><strong>Los que compraron d\u00f3lar MEP o CCL en los \u00faltimos 90 d\u00edas<\/strong><\/h3>\n<p>Aquellas personas que hayan comprado d\u00f3lares a trav\u00e9s del banco en los \u00faltimos 90 d\u00edas.\n<\/p>\n<h3><strong>2. Trabajadores de empresas que recibieron ATP<\/strong><\/h3>\n<p>Los empleados que cobraron parte de su sueldo gracias al aporte del Estado gracias al programa ATP, no podr\u00e1n comprar d\u00f3lares. El ATP era un programa que formaba parte de la asistencia social en el marco de la pandemia.\n<\/p>\n<h3><strong>3. Beneficiarios de IFE &#8211; AUH y el resto de los planes sociales<\/strong><\/h3>\n<p><span>Se trata de la medida m\u00e1s relevante: millones de personas dejaron de comprar billetes verdes. Hay que tener en cuenta que hay 8,9 millones de beneficiarios del IFE. El Gobierno ya hab\u00eda analizado la posibilidad de cortarles la chance de la compra de<strong> d\u00f3lares &#8220;ahorro&#8221;,<\/strong> pero en su momento se cajone\u00f3 esa idea para no dejar sin abastecimiento al mercado &#8220;paralelo&#8221;. Ahora que la ca\u00edda de las reservas no puede detenerse, el Gobierno decidi\u00f3 bloquear el acceso a los beneficiarios de planes sociales.<\/span>\n<\/p>\n<h3>4. Cotitulares de cuentas bancarias<\/h3>\n<p><span>Es otra de las medidas importantes. En principio, las compras de d\u00f3lares pod\u00edan hacerlas dos personas que compartieran una misma cuenta bancaria. Se computaba por el <strong>CUIT o el CUIL<\/strong>. Actualmente esa chance desapareci\u00f3. Y s\u00f3lo puede comprar una persona por cuenta bancaria.&nbsp;<\/span>\n<\/p>\n<h3>5. Los que hayan refinanciado cuotas de cr\u00e9ditos personales, prendarios o hipotecarios<\/h3>\n<p><span>Quedan afuera los clientes que no pudieron pagar los<strong> vencimientos<\/strong> y se vieron obligados a postergar las cuotas hasta el final del cr\u00e9dito.<\/span>\n<\/p>\n<h3>6. Los que hayan refinanciado el saldo de la tarjeta de cr\u00e9dito a 12 meses<\/h3>\n<p><span>Son m\u00e1s de <strong>dos millones de personas<\/strong> que utilizaron esa posibilidad: de no pagar ahora los vencimientos y postergarlos en el tiempo, a una tasa nominal anual del 40% m\u00e1s IVA.<\/span>\n<\/p>\n<div class=\"imagen\">\n<div class=\"imagen\">\n<div class=\"imagen\" readability=\"6\">\n<div class=\"imagen\" readability=\"7\"><img decoding=\"async\" loading=\"lazy\" class=\"lazyload\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/04\/como-saber-si-estoy-inhabilitado-para-comprar-dolares-4.jpg\" alt=\"Qui\u00e9nes quedan excluidos del acceso al d\u00f3lar oficial\" width=\"880\" height=\"495\"><\/p>\n<p>Qui\u00e9nes quedan excluidos del acceso al d\u00f3lar oficial<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h3>7. No tengan ingresos declarados<\/h3>\n<p><span>Se trata de otra restricci\u00f3n relevante: antes de autorizar la venta de d\u00f3lares, los bancos est\u00e1n obligados a consultar la base de datos para saber si su cliente tiene ingresos declarados. Al respecto, el BCRA hab\u00eda detectado que desde 1,2 mill\u00f3n de cuentas se compraban divisas pero se trataba de personas que durante el resto del mes no mostraban actividad. S\u00f3lo aparec\u00eda un dep\u00f3sito mensual para la adquisici\u00f3n de divisas. <\/span>\n<\/p>\n<p><span>La sospecha es clara: que son compradores con ingresos &#8220;en negro&#8221;, sin declarar, y que actualmente no pueden comprar billetes verdes.<\/span>\n<\/p>\n<h3><strong>8. Beneficiarios de subsidios energ\u00e9ticos<\/strong><\/h3>\n<p>Los que hayan solicitado el subsidio a la energ\u00eda electrica y\/o al gas natural.&nbsp;\n<\/p>\n<h3><strong>9. Monotributistas que tengan en curso cr\u00e9ditos a tasa subsidiada<\/strong><\/h3>\n<h3><strong>10. Los que hayan pagado en d\u00f3lares plataformas como Spotify y Netflix con la tarjeta de cr\u00e9dito<\/strong><\/h3>\n<p>Las personas que hayan gastado el cupo de d\u00f3lares permitido pagando plataformas como Spotify y Netflix no podr\u00e1n comprar m\u00e1s.&nbsp;\n<\/p>\n<h3>11. Beneficiarios del refuerzo de ingresos que se pag\u00f3 en mayo y junio de 2022.<\/h3>\n<h2>Qu\u00e9 hacer con los d\u00f3lares manchados, sucios o rotos<\/h2>\n<p>Uno de los graves problemas que surgen al comprar d\u00f3lares se da si recibimos un<span> <strong>billete manchado<\/strong>, sucio o roto.&nbsp;<\/span>\n<\/p>\n<p>Los argentinos seguramente seamos de los m\u00e1s interesados la divisa estadounidense. O al menos, vivimos pendientes de su cotizaci\u00f3n para ahorrar, invertir o, tambi\u00e9n, irnos de viaje. Es tan grande el inter\u00e9s como lo es tambi\u00e9n la desesperaci\u00f3n cuando descubrimos que tenemos d\u00f3lares rotos, manchados, deteriorados o, incluso, los &#8220;cara chica&#8221;.\n<\/p>\n<p>\u00bfQu\u00e9 hacemos? \u00bfLos tiramos? \u00bfSirven todav\u00eda? Lo primero que debemos saber es que los billetes <strong>deteriorados, <\/strong>sirven o <span>se pueden canjear por papeles nuevos.<\/span>\n<\/p>\n<div class=\"imagen\" readability=\"8\"><img decoding=\"async\" loading=\"lazy\" class=\"lazyload\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/04\/como-saber-si-estoy-inhabilitado-para-comprar-dolares-5.jpg\" alt=\"Qu\u00e9 hacer con los d\u00f3lares manchados, sucios o rotos\" width=\"941.6\" height=\"627.725\"><\/p>\n<p>Qu\u00e9 hacer con los d\u00f3lares manchados, sucios o rotos<\/p>\n<\/div>\n<p>Por supuesto, <strong>deben estar dentro de ciertos par\u00e1metros de conservaci\u00f3n<\/strong>. Y, en ese sentido,<span> su presentaci\u00f3n resultar\u00e1 clave para que los d\u00f3lares sean recibidos en alguna operaci\u00f3n. <\/span>\n<\/p>\n<p>Los d\u00f3lares manchados o deteriorados se pueden cambiar por billetes nuevos siempre y cuando se pueda reunir e identificar al menos el 80% del billete. Adem\u00e1s, es necesario que <strong>est\u00e9n visibles y entendibles<\/strong> todos los elementos de seguridad y el n\u00famero de serie del billete.\n<\/p>\n<p>&#8220;En l\u00edneas generales, los bancos argentinos importan de Estados Unidos d\u00f3lares americanos en billetes, pero en muy pocas ocasiones realizan exportaciones de los mismos&#8221;, explicaron a <strong>iProfesional<\/strong> desde Banco Piano, una de las entidades m\u00e1s representativas de Argentina en el<a href=\"https:\/\/www.iprofesional.com\/politica\/354076-gobierno-acusacion-de-sabotaje-y-apriete-a-las-provincias\" target=\"_blank\" rel=\"noopener\"> segmento de cambio de monedas<\/a>.\n<\/p>\n<p>Y agregaron que &#8220;es por este motivo que las entidades generalmente <strong>no aceptan d\u00f3lares<\/strong> que se encuentren manchados, da\u00f1ados o escritos, ya que estar\u00edan obligados a exportarlos dado que no pueden entregar billetes en mal estado a ahorristas que los retiren por ventanilla&#8221;.\n<\/p>\n<p>Por tal motivo, <span>quien se presente en una sucursal con un ejemplar que no se encuentre en \u00f3ptimas condiciones, tiene altas probabilidades de que le sea rechazado<\/span>.\n<\/p>\n<p>&#8220;Este es un inconveniente que se repite en la mayor\u00eda de los pa\u00edses lim\u00edtrofes y tambi\u00e9n en otros de la regi\u00f3n, dado que la <strong>media o baja bancarizaci\u00f3n<\/strong> y el ahorro dom\u00e9stico generan este tipo de problemas con los billetes que no son de circulaci\u00f3n en el respectivo pa\u00eds&#8221;, completaron desde la instituci\u00f3n a este medio, y subrayaron la vital importancia que tiene que este tipo de operaciones sean realizadas &#8220;en entidades habilitadas y supervisadas por el Banco Central, por el riesgo que implica el manejo de efectivo y toda la seguridad asociada a la operaci\u00f3n&#8221;.\n<\/p>\n<p>Al ser consultados sobre la legislaci\u00f3n que alcanza a estos billetes, desde Banco Piano explicaron <strong>que no existe ninguna normativa que obligue a los bancos <\/strong>a aceptar d\u00f3lares que se encuentren escritos, o bien con cierto da\u00f1o.\n<\/p>\n<p>&#8220;Hay legislaci\u00f3n sobre <strong>pesos argentinos<\/strong>, y justamente los bancos son los responsables de separar los billetes que no se encuentran en condiciones de circular, entregando los mismos al Banco Central de la Rep\u00fablica Argentina&#8221;, aclararon.\n<\/p>\n<p>En cuanto a comisiones, las entidades que aceptan estos billetes cobran generalmente un porcentaje de la operaci\u00f3n, ya que deben cubrir <strong>gastos de exportaci\u00f3n<\/strong> de estos y adicionalmente tambi\u00e9n tienen que afrontar los gastos de importaci\u00f3n de nuevas unidades.\n<\/p>\n<p>Esa comisi\u00f3n puede variar de acuerdo al estado de deterioro de los billetes, pero en el mercado formal <span>puede llegar a un 20% del monto canjeado.<\/span>\n<\/p>\n<h2>D\u00f3lares deteriorados por estar &#8220;mal escondidos&#8221;<\/h2>\n<p>En efecto, no siempre se llega a un buen resultado al momento de <strong>encontrar el mejor escondite donde guardar los d\u00f3lares. <\/strong>Sin embargo, <a href=\"https:\/\/www.iprofesional.com\/dinero\/354072-fmi-gasto-y-tarifas-procrastinar-tiene-altos-costos\" target=\"_blank\" rel=\"noopener\">detr\u00e1s de esa originalidad, desatendemos otros factores que pueden deteriorar los billetes<\/a>.\n<\/p>\n<p>Desde <strong>la humedad ambiente o las filtraciones de agua, hasta insectos o roedores,<\/strong> todos son aspectos de riesgo para los d\u00f3lares que pueden terminar con los billetes <strong>manchados, rotos, perforados, gastados o mordidos<\/strong>. Tambi\u00e9n puede ocurrir que al recibir un papel de divisa no nos dimos cuenta que<span> estaba rayado o marcado con alguna tinta<\/span>.\n<\/p>\n<p>En definitiva, son todos efectos que no deseamos encontrar en nuestros billetes de d\u00f3lar. En cuanto lo percibimos, ya puede ser tarde.\n<\/p>\n<h2>Qu\u00e9 se considera un d\u00f3lar deteriorado<\/h2>\n<ul>\n<li><span>D\u00f3lares manchados (con tinta, pintura, etc.).<\/span><\/li>\n<li>D\u00f3lares muy desgastados por el uso.<\/li>\n<li>D\u00f3lares cortados o mutilados.<\/li>\n<li>D\u00f3lares rotos o ajados.<\/li>\n<li>D\u00f3lares quemados.<\/li>\n<li>D\u00f3lares sucios.<\/li>\n<li><strong>D\u00f3lares ro\u00eddos por roedores.<\/strong><\/li>\n<li>D\u00f3lares comidos por insectos.<\/li>\n<li>D\u00f3lares mordidos por animales.<\/li>\n<li>D\u00f3lares h\u00famedos o mojados.<\/li>\n<li><span>D\u00f3lares con putrefacci\u00f3n (esto ocurre cuando fueron enterrados).<\/span><\/li>\n<li>D\u00f3lares enmohecidos.<\/li>\n<li>D\u00f3lares escritos o marcados con birome o fibra.<\/li>\n<li>D\u00f3lares petrificados.<\/li>\n<li>D\u00f3lares da\u00f1ados por alg\u00fan compuesto qu\u00edmico.<\/li>\n<\/ul>\n<h2>\u00bfLlevamos los d\u00f3lares deteriorados al banco?<\/h2>\n<p>Llegados a este punto, una primera alternativa ser\u00eda<span> ir a cualquier banco a depositar nuestros d\u00f3lares manchados para, luego, retirar billetes nuevos.<\/span>&nbsp;\n<\/p>\n<div class=\"imagen\" readability=\"8\"><img decoding=\"async\" loading=\"lazy\" class=\"lazyload\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/04\/como-saber-si-estoy-inhabilitado-para-comprar-dolares-6.jpg\" alt=\"D\u00f3lares manchados, sucios o rotos: qu\u00e9 se considera un d\u00f3lar deteriorado\" width=\"722\" height=\"435\"><\/p>\n<p>D\u00f3lares manchados, sucios o rotos: qu\u00e9 se considera un d\u00f3lar deteriorado<\/p>\n<\/div>\n<p>Cabe tener presente que<strong> los bancos argentinos no est\u00e1n obligados a recibir d\u00f3lares<\/strong> -u otra moneda extranjera- en mal estado. Y si bien esta opci\u00f3n puede funcionar, lo m\u00e1s probable<span> es que los billetes sean rechazados. <\/span>En todo caso,<a href=\"https:\/\/www.iprofesional.com\/impuestos\/354036-reduccion-de-ganancias-cuantas-empresas-no-pueden-justificarla\" target=\"_blank\" rel=\"noopener\"> depender\u00e1 del estado en que se encuentren los papeles.<\/a>\n<\/p>\n<p>Los bancos o entidades financieras <span>rebotan los d\u00f3lares porque despu\u00e9s, seguramente, ning\u00fan otro cliente quiera recibir esos billetes<\/span> y, qued\u00e1rselos, implica que deber\u00e1n exportarlos para canjearlos, absorbiendo los elevados costos que eso representa. Ning\u00fan banco quiere eso.\n<\/p>\n<p>Por lo tanto, son muy exigentes para<strong> cambiar los d\u00f3lares viejos por nuevos<\/strong>, si no est\u00e1n en perfectas condiciones. Lo m\u00e1s probable es que si est\u00e1n escritos, rotos o manchados, no sean tomados por la entidad bancaria.\n<\/p>\n<h2>Recomendaciones<\/h2>\n<p>En primer lugar,<span> es fundamental revisar bien los billetes cuando los recibimos y no aceptarlos en ninguna transacci\u00f3n financiera<\/span> o comercial si est\u00e1n manchados, escritos, deteriorados, quemados, muy gastados o, incluso, si se trata de una serie vieja, los denominados d\u00f3lares &#8220;cara chica&#8221;. Por todas estas cuestiones, en operaciones futuras o en ciertos lugares,<strong> puede que no nos acepten esos mismos billetes<\/strong>.\n<\/p>\n<div class=\"tepuedeinteresar\">\n<p>Te puede interesar<\/p>\n<\/p><\/div>\n<p>En segundo t\u00e9rmino, en la ciudad de Buenos Aires,<span> existen agencias de cambio que ofrecen canjear billetes de d\u00f3lares en mal estado. <\/span>En este caso, es clave tomar los recaudos necesarios para chequear <strong>que no se trata de una estafa,<\/strong> para lo cual, como primera medida, se debe verificar que la agencia est\u00e9 regulada y acreditada por el Banco Central de la Rep\u00fablica Argentina (BCRA).<\/p>\n","protected":false},"excerpt":{"rendered":"\n<div class=\"media_block\"><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/04\/como-saber-si-estoy-inhabilitado-para-comprar-dolares.jpg\"><\/div>\n<p> El d\u00f3lar ahorro, MEP y CCL cada vez con m\u00e1s restricciones. Quienes est\u00e1n habilitados a comprar y c\u00f3mo saber si podes adquirir. <iframe width=\"0\" height=\"0\" border=\"0\"> <script> (function(i,s,o,g,r,a,m){i['GoogleAnalyticsObject']=r;i[r]=i[r]||function(){ (i[r].q=i[r].q||[]).push(arguments)},i[r].l=1*new Date();a=s.createElement(o), m=s.getElementsByTagName(o)[0];a.async=1;a.src=g;m.parentNode.insertBefore(a,m) })(window,document,'script','https:\/\/www.google-analytics.com\/analytics.js','ga'); ga('create', 'GTM-5LW5KQD', 'auto'); ga('require', 'displayfeatures'); ga('set', 'campaignSource', 'RSS Client for iProfesional'); ga('set', 'campaignMedium', 'RSS Client for iProfesional'); ga('set', {\"dataSource\": \"rss.atom.iprofesional.com\"}); ga('set', {\"referrer\": \"rss.atom.iprofesional.com\"}); ga('set', 'title', 'RSS Client for iProfesional'); ga('send', 'pageview'); <\/script> <!-- Begin comScore Tag --> <script> var _comscore = _comscore || []; _comscore.push({ c1: \"2\", c2: \"37240992\" }); (function() { var s = document.createElement(\"script\"), el = document.getElementsByTagName(\"script\")[0]; s.async = true; s.src = \"https:\/\/sb.scorecardresearch.com\/cs\/37240992\/beacon.js\"; el.parentNode.insertBefore(s, el); })(); <\/script> <noscript> <img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2023\/04\/como-saber-si-estoy-inhabilitado-para-comprar-dolares.gif\"> <\/noscript> <!-- End comScore Tag --> <\/iframe>  <\/p>\n","protected":false},"author":1,"featured_media":7464,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/7463"}],"collection":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/comments?post=7463"}],"version-history":[{"count":0,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/7463\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media\/7464"}],"wp:attachment":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media?parent=7463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/categories?post=7463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/tags?post=7463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}