{"id":40904,"date":"2026-03-16T20:24:00","date_gmt":"2026-03-16T20:24:00","guid":{"rendered":"https:\/\/www.iprofesional.com\/negocios\/450335-caramelos-importados-georgalos-fabrica-china-caramelos-masticables-emblematicos"},"modified":"2026-03-16T20:24:00","modified_gmt":"2026-03-16T20:24:00","slug":"icono-de-las-golosinas-cambia-de-origen-georgalos-fabrica-en-china-uno-de-sus-caramelos-mas-famosos","status":"publish","type":"post","link":"https:\/\/latecordoba.com\/index.php\/2026\/03\/16\/icono-de-las-golosinas-cambia-de-origen-georgalos-fabrica-en-china-uno-de-sus-caramelos-mas-famosos\/","title":{"rendered":"\u00cdcono de las golosinas cambia de origen: Georgalos fabrica en China uno de sus caramelos m\u00e1s famosos"},"content":{"rendered":"\n<div class=\"media_block\"><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2026\/03\/icono-de-las-golosinas-cambia-de-origen-georgalos-fabrica-en-china-uno-de-sus-caramelos-mas-famosos.jpg\"><\/div>\n<div><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2026\/03\/icono-de-las-golosinas-cambia-de-origen-georgalos-fabrica-en-china-uno-de-sus-caramelos-mas-famosos.webp\" class=\"ff-og-image-inserted\"><\/div>\n<p>El presidente de <strong>Georgalos<\/strong>, <a href=\"https:\/\/www.iprofesional.com\/negocios\/428138-georgalos-pone-en-venta-al-mantecol-y-a-todas-sus-golosinas-ante-una-crisis-de-consumo\" target=\"_blank\" rel=\"noopener noreferrer\">Miguel Zonnaras, admiti\u00f3 que ya fabrica en China<\/a> una de las golosinas m\u00e1s emblem\u00e1ticas de la compa\u00f1\u00eda: los <strong>caramelos masticables Flynn Paff<\/strong>. La producci\u00f3n se realiza en el pa\u00eds asi\u00e1tico y luego se importa para su comercializaci\u00f3n en el mercado argentino.<\/p>\n<p>El anuncio lleg\u00f3 en medio del debate sobre apertura importadora y competitividad industrial. Zonnaras lo confirm\u00f3 en di\u00e1logo con La F\u00e1brica Podcast, donde explic\u00f3 las razones detr\u00e1s de esta decisi\u00f3n empresarial.<\/p>\n<p>&#8220;Yo soy de ADN industrial, pero tambi\u00e9n muy pragm\u00e1tico en el sentido de que el proyecto tiene que ser rentable y sustentable en el tiempo&#8221;, dijo el empresario al justificar el cambio de estrategia productiva.<\/p>\n<p><span>La decisi\u00f3n responde a <a href=\"https:\/\/www.iprofesional.com\/negocios\/428142-la-verdad-sobre-la-supuesta-crisis-de-georgalos-empresa-duena-de-mantecol\" target=\"_blank\" rel=\"noopener noreferrer\">la p\u00e9rdida de competitividad de la industria local<\/a><strong><\/strong> frente a factores estructurales como la presi\u00f3n impositiva, los costos log\u00edsticos y la infraestructura precaria.<\/span><\/p>\n<h2>Por qu\u00e9 los caramelos emblem\u00e1ticos de Georgalos ya se fabrican en China<\/h2>\n<p>Zonnaras desminti\u00f3 una creencia extendida en el sector alimenticio. Muchos suponen que producir en pa\u00edses con materias primas da una ventaja competitiva autom\u00e1tica.<\/p>\n<p>Sin embargo, el presidente de Georgalos sostiene que esas materias primas se &#8220;comoditizaron&#8221;. <strong>Se comercializan a precios internacionales similares<\/strong> en cualquier mercado del mundo.<\/p>\n<p>&#8220;\u00bfQu\u00e9 implica esto para Do\u00f1a Rosa? Que el costo de la materia prima para nosotros es pr\u00e1cticamente el mismo que en cualquier parte del mundo. \u00bfPor qu\u00e9? Porque es una commodity&#8221;, se\u00f1al\u00f3.<\/p>\n<p>Al ser una commodity, el precio al que ingresa a una f\u00e1brica es pr\u00e1cticamente igual sin importar d\u00f3nde est\u00e9 ubicada. La ventaja de tener az\u00facar o glucosa local se evapora cuando esos insumos cotizan a valor internacional.<\/p>\n<p>Algo similar ocurri\u00f3 con la tecnolog\u00eda. &#8220;La tecnolog\u00eda tambi\u00e9n se comoditiz\u00f3. <strong>Hoy ya no hay grandes diferencias tecnol\u00f3gicas<\/strong> entre un productor y otro&#8221;, afirm\u00f3 el empresario.<\/p>\n<p><span>Lo que termina determinando la competitividad no es la materia prima ni la tecnolog\u00eda, sino el resto de los factores que intervienen en la producci\u00f3n: <strong>intervenci\u00f3n estatal, infraestructura y log\u00edstica<\/strong>.<\/span><\/p>\n<h2>Cu\u00e1nto cuesta traer caramelos desde China versus producirlos en Argentina<\/h2>\n<p>Para ilustrar la distorsi\u00f3n de costos, Zonnaras mencion\u00f3 los valores del transporte mar\u00edtimo. Un flete desde China a Buenos Aires cuesta hoy alrededor de u$s4.000.<\/p>\n<p>Desde C\u00f3rdoba hasta Buenos Aires, <strong>el transporte ronda los u$s2.000<\/strong>. Es decir, mover mercader\u00eda dentro del pa\u00eds puede resultar m\u00e1s barato que traerla desde Asia, pero la ecuaci\u00f3n total sigue favoreciendo al exterior.<\/p>\n<p>&#8220;Cuando uno va a las ferias mundiales encuentra proveedores de todo el mundo que producen exactamente los mismos productos. Muchas veces lo \u00fanico que hay que pedirles es que cambien el envoltorio, el papel o la marca, y el producto est\u00e1 listo para traer&#8221;, describi\u00f3.<\/p>\n<p>El empresario resalt\u00f3 que Argentina enfrenta un problema de infraestructura. &#8220;Tenemos una infraestructura muy, pero muy precaria respecto a c\u00f3mo se manejan los pa\u00edses industriales en el mundo y sus costos de log\u00edstica&#8221;, asegur\u00f3.<\/p>\n<p>En algunos casos, trasladar mercader\u00eda dentro del pa\u00eds resulta m\u00e1s caro que importarla. <strong>La log\u00edstica interna se convirti\u00f3 en un obst\u00e1culo<\/strong> para la competitividad industrial.<\/p>\n<h2>La presi\u00f3n impositiva que hace inviable la producci\u00f3n local<\/h2>\n<p>Zonnaras fue contundente al se\u00f1alar que la carga tributaria provincial y municipal termina de hundir la competitividad. &#8220;Es dif\u00edcil ser competitivo cuando encima el productor local le tiene que agregar los impuestos de municipios y provincias, y el que trae productos del exterior no tiene esa sobrecarga&#8221;, remarc\u00f3.<\/p>\n<p>El problema no se resuelve con bajas de impuestos nacionales. &#8220;De nada me sirve que Naci\u00f3n me baje los impuestos si las provincias y los municipios me los suben&#8221;, sostuvo.<\/p>\n<p><span>El empresario advirti\u00f3 que <strong>la sobrepresi\u00f3n impositiva se traslada al producto final<\/strong>, y cuando ese producto no logra ser competitivo, el impacto termina sinti\u00e9ndose en el empleo y el consumo, generando un c\u00edrculo vicioso.<\/span><\/p>\n<p>&#8220;Estamos en un gran problema estructural, porque algunos en la pol\u00edtica se endilgan de que bajan los impuestos, pero otros, si no les llegan los recursos de los otros estamentos del estado, tienen que sobrevivir&#8221;, explic\u00f3.<\/p>\n<p>La descoordinaci\u00f3n fiscal entre niveles de gobierno genera una trampa para el sector productivo. <strong>Lo que se ahorra en un nivel se pierde en otro<\/strong>, sin que el productor pueda planificar con certeza.<\/p>\n<h2>El conflicto laboral que atraves\u00f3 Georgalos en 2025<\/h2>\n<p>En junio de 2025, la planta de Georgalos ubicada en Victoria, Buenos Aires, atraves\u00f3 un conflicto laboral significativo. Los trabajadores realizaron un corte parcial en el ramal Tigre de la Autopista Panamericana.<\/p>\n<p>La protesta fue motivada por <strong><a href=\"https:\/\/www.iprofesional.com\/negocios\/430441-georgalos-no-acato-la-conciliacion-hay-despidos-y-empleados-cortan-panamericana\" target=\"_blank\" rel=\"noopener noreferrer\">el despido de cinco empleados<\/a><\/strong>, la eliminaci\u00f3n del bono por productividad y diferencias en las condiciones laborales con otras plantas del sector.<\/p>\n<p>Los trabajadores reclamaron la reincorporaci\u00f3n de los despedidos. El incidente puso en evidencia las tensiones que genera la reestructuraci\u00f3n productiva en un contexto de deslocalizaci\u00f3n industrial.<\/p>\n<p>Georgalos enfrenta ahora el desaf\u00edo de mantener su presencia en el mercado argentino mientras busca equilibrar costos y rentabilidad. <strong>La producci\u00f3n en China de Flynn Paff<\/strong> es solo una pieza de una estrategia m\u00e1s amplia para sobrevivir en un entorno econ\u00f3mico adverso.<\/p>\n","protected":false},"excerpt":{"rendered":"\n<div class=\"media_block\"><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2026\/03\/icono-de-las-golosinas-cambia-de-origen-georgalos-fabrica-en-china-uno-de-sus-caramelos-mas-famosos.jpg\"><\/div>\n<p> El l\u00edder de la compa\u00f1\u00eda explic\u00f3 que trasladar la producci\u00f3n al exterior responde a la suba de costos y desaf\u00edos de la industria alimenticia local <iframe width=\"0\" height=\"0\" border=\"0\"> <script> (function(i,s,o,g,r,a,m){i['GoogleAnalyticsObject']=r;i[r]=i[r]||function(){ (i[r].q=i[r].q||[]).push(arguments)},i[r].l=1*new Date();a=s.createElement(o), m=s.getElementsByTagName(o)[0];a.async=1;a.src=g;m.parentNode.insertBefore(a,m) })(window,document,'script','https:\/\/www.google-analytics.com\/analytics.js','ga'); ga('create', 'GTM-5LW5KQD', 'auto'); ga('require', 'displayfeatures'); ga('set', 'campaignSource', 'RSS Client for iProfesional'); ga('set', 'campaignMedium', 'RSS Client for iProfesional'); ga('set', {\"dataSource\": \"rss.atom.iprofesional.com\"}); ga('set', {\"referrer\": \"rss.atom.iprofesional.com\"}); ga('set', 'title', 'RSS Client for iProfesional'); ga('send', 'pageview'); <\/script> <!-- Begin comScore Tag --> <script> var _comscore = _comscore || []; _comscore.push({ c1: \"2\", c2: \"16597048\" }); (function() { var s = document.createElement(\"script\"), el = document.getElementsByTagName(\"script\")[0]; s.async = true; s.src = \"https:\/\/sb.scorecardresearch.com\/cs\/16597048\/beacon.js\"; el.parentNode.insertBefore(s, el); })(); <\/script> <noscript> <img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2026\/03\/icono-de-las-golosinas-cambia-de-origen-georgalos-fabrica-en-china-uno-de-sus-caramelos-mas-famosos.gif\"> <\/noscript> <!-- End comScore Tag --> <\/iframe> <iframe border=\"0px\" style=\"display: none\" width=0 height=0 src=\"https:\/\/www.iprofesional.com\/ga4.html?gtag_id=G-N13KWJP8BK&amp;title=\u00cdcono de las golosinas cambia de origen: Georgalos fabrica en China uno de sus caramelos m\u00e1s famosos&amp;location=https:\/\/www.iprofesional.com\/negocios\/450335-caramelos-importados-georgalos-fabrica-china-caramelos-masticables-emblematicos&amp;referrer=rss.atom.iprofesional.com&amp;ci=RSS Client for iProfesional&amp;cs=RSS Client for iProfesional&amp;cm=RSS&amp;cn=RSS Client for iProfesional&amp;cc=RSS Client for iProfesional\"><\/iframe>  <\/p>\n","protected":false},"author":1,"featured_media":40905,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/40904"}],"collection":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/comments?post=40904"}],"version-history":[{"count":0,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/40904\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media\/40905"}],"wp:attachment":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media?parent=40904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/categories?post=40904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/tags?post=40904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}