{"id":30338,"date":"2024-12-29T15:01:34","date_gmt":"2024-12-29T15:01:34","guid":{"rendered":"https:\/\/www.vitonica.com\/entrenamiento\/olvidate-ejercicios-basicos-estas-incluyendo-tu-rutina-esta-razon"},"modified":"2024-12-29T15:01:34","modified_gmt":"2024-12-29T15:01:34","slug":"olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon","status":"publish","type":"post","link":"https:\/\/latecordoba.com\/index.php\/2024\/12\/29\/olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon\/","title":{"rendered":"Olv\u00eddate de los ejercicios b\u00e1sicos si los est\u00e1s incluyendo en tu rutina por esta raz\u00f3n"},"content":{"rendered":"\n<p>Azuzada por el \u00e9xito del powerlifting en los \u00faltimos a\u00f1os existe una creencia que consiste en pensar que hacerse fuerte en los ejercicios b\u00e1sicos (<a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/guia-completa-para-mejorar-sentadilla-como-entrenar-para-levantar-peso\" data-vars-post-title=\"Gu\u00eda completa para mejorar en sentadilla: c\u00f3mo entrenar para levantar m\u00e1s peso \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/guia-completa-para-mejorar-sentadilla-como-entrenar-para-levantar-peso\">sentadilla<\/a>, <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/guia-completa-para-mejorar-ejercicio-fisico-press-banca-asi-puedes-romper-tus-records\" data-vars-post-title=\"Gu\u00eda completa para mejorar en press banca: as\u00ed puedes romper tus r\u00e9cords\" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/guia-completa-para-mejorar-ejercicio-fisico-press-banca-asi-puedes-romper-tus-records\">press de banca<\/a> o <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/guia-completa-para-mejorar-peso-muerto-como-entrenar-para-conseguir-mejor-levantamiento\" data-vars-post-title=\"Gu\u00eda completa para mejorar en peso muerto: c\u00f3mo entrenar para conseguir un mejor levantamiento \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/guia-completa-para-mejorar-peso-muerto-como-entrenar-para-conseguir-mejor-levantamiento\">peso muerto<\/a>) es primordial para aquellos que desean ganar masa muscular, ya sea en amateurs o en culturistas competidores.&nbsp;<\/p>\n<p><!-- BREAK 1 --> <\/p>\n<p>Las personas que comulgan con este pensamiento creen que la ganancia de fuerza obtenida en estos ejercicios puede transferirse a otros, generalmente de aislamiento, y que por lo tanto al levantar m\u00e1s peso en estos, esto se traduzca en mayor est\u00edmulo para la hipertrofia.&nbsp;<\/p>\n<p><!-- BREAK 2 --><\/p>\n<p>Dicho esto, en este art\u00edculo <strong>vamos a explicarte qu\u00e9 puedes esperar de los ejercicios b\u00e1sicos si los incluyes en tu rutina de entrenamiento.&nbsp;<\/strong><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.vitonica.com\/entrenamiento\/estabamos-equivocados-ejercicios-basicos-para-ganar-masa-muscular\" class=\"pivot-outboundlink\" data-vars-post-title=\"Est\u00e1bamos equivocados con los ejercicios b\u00e1sicos para ganar masa muscular \"> <img decoding=\"async\" loading=\"lazy\" alt=\"Est\u00e1bamos equivocados con los ejercicios b\u00e1sicos para ganar masa muscular \" width=\"375\" height=\"142\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/12\/olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon.webp\" onerror=\"this.src=&quot;https:\/\/i.blogs.es\/6652b0\/danielle-cerullo-oo-rhghlnha-unsplash-3-\/375_142.jpeg&quot;\"> <\/a> <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"video-boost-container article-asset-normal\">\n<div class=\"article-asset-video\">\n<div class=\"asset-content\">\n<p> <iframe loading=\"lazy\" width=\"650\" height=\"366\" src=\"https:\/\/www.youtube.com\/embed\/zyPYe1jyJqc\" allowfullscreen>[embedded content]<\/iframe> <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p> <span class=\"video-boost-title\">La importancia del entrenamiento de fuerza en las mujeres | Se me cae un mito<\/span>\n<\/div>\n<h2>\u00bfSi te haces fuerte en los b\u00e1sicos hipertrofias m\u00e1s con otros ejercicios?<\/h2>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"> <img class=\"centro_sinmarco\" height=\"1603\" width=\"2400\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/12\/olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon-1.webp 450w, http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/12\/olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon-4.webp 681w, http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/12\/olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon-5.webp 1024w, https:\/\/i.blogs.es\/12cc46\/gordon-cowie-sgrfzxsyrdw-unsplash-7-\/1366_2000.webp 1366w\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/12\/olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon-1.webp\" alt=\"Gordon Cowie Sgrfzxsyrdw Unsplash 7\" onerror=\"this.src='https:\/\/i.blogs.es\/12cc46\/gordon-cowie-sgrfzxsyrdw-unsplash-7-\/450_1000.jpeg';this.srcset='https:\/\/i.blogs.es\/12cc46\/gordon-cowie-sgrfzxsyrdw-unsplash-7-\/450_1000.jpeg 450w, https:\/\/i.blogs.es\/12cc46\/gordon-cowie-sgrfzxsyrdw-unsplash-7-\/650_1200.jpeg 681w,https:\/\/i.blogs.es\/12cc46\/gordon-cowie-sgrfzxsyrdw-unsplash-7-\/1024_2000.jpeg 1024w, https:\/\/i.blogs.es\/12cc46\/gordon-cowie-sgrfzxsyrdw-unsplash-7-\/1366_2000.jpeg 1366w';return false;\"> <noscript><img decoding=\"async\" alt=\"Gordon Cowie Sgrfzxsyrdw Unsplash 7\" class=\"centro_sinmarco\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/12\/olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon-1.webp\"><\/noscript> <\/div>\n<\/div>\n<p>Imaginemos por un instante que somos capaces de levantar en enero 100 kilos en press de banca. Tras unos cuantos meses mejoramos y somos capaces de levantar 125 kilos. Dado que ahora rendimos mejor en banca, \u00bftendr\u00edamos m\u00e1s facilidad para hipertrofiar nuestros <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/consigue-unos-pectorales-fuertes-esta-seleccion-ejercicios\" data-vars-post-title=\"Consigue unos pectorales fuertes con esta selecci\u00f3n de ejercicios \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/consigue-unos-pectorales-fuertes-esta-seleccion-ejercicios\">pectorales<\/a>, <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/seleccion-ejercicios-que-tienes-que-tener-cuenta-para-fortalecer-entrenar-triceps\" data-vars-post-title=\"La selecci\u00f3n de ejercicios que tienes que tener en cuenta para fortalecer y entrenar los tr\u00edceps \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/seleccion-ejercicios-que-tienes-que-tener-cuenta-para-fortalecer-entrenar-triceps\">tr\u00edceps<\/a> o <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/seleccion-ejercicios-que-necesitas-para-trabajar-deltoides\" data-vars-post-title=\"La selecci\u00f3n de ejercicios que necesitas para trabajar los deltoides \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/seleccion-ejercicios-que-necesitas-para-trabajar-deltoides\">deltoides anteriores<\/a> al poder, presuntamente, levantar m\u00e1s peso en otros ejercicios?<\/p>\n<p><!-- BREAK 3 --> <\/p>\n<p>Planteamos esto porque existe una creencia que defiende que la fuerza ganada en ejercicios b\u00e1sicos se puede transferir a otros ejercicios, de aislamiento por lo general, y que por lo tanto al levantar m\u00e1s peso en estos el est\u00edmulo para hipertrofia es mayor. Veamos por qu\u00e9 esto no es as\u00ed.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<ul>\n<li>En primer lugar, <strong>la fuerza es espec\u00edfica<\/strong>, es decir, si hacemos press de banca mejoramos en press de banca. Esta pr\u00e1ctica de la banca puede hacer que ganemos masa muscular o que mejoremos la activaci\u00f3n voluntaria de las fibras de nuestro pectoral y que esto se pueda transferir a otros ejercicios similares, pero <strong>realmente podr\u00eda pasar con cualquier otro ejercicio, no solo con la banca.<\/strong><\/li>\n<li>En segundo lugar, aunque la fuerza ganada en press de banca implicara que pudi\u00e9ramos hacer, por ejemplo, cruce de poleas con m\u00e1s peso, esto no se traduce en m\u00e1s hipertrofia porque el est\u00edmulo de hipertrofia no depende del peso usado sino del esfuerzo creciente hacia el final de una serie y de la <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/importancia-ultimas-repeticiones-durante-serie-cuando-buscamos-hipertrofia\" data-vars-post-title=\"Si buscas conseguir hipertrofia, presta especial atenci\u00f3n a las \u00faltimas repeticiones: la clave est\u00e1 en la relaci\u00f3n fuerza-velocidad\" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/importancia-ultimas-repeticiones-durante-serie-cuando-buscamos-hipertrofia\">p\u00e9rdida en la velocidad de acortamiento<\/a> de nuestras fibras musculares.<\/li>\n<\/ul>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.vitonica.com\/entrenamiento\/muchas-series-muy-cerca-fallo-esto-debes-saber-a-hora-entrenar-te-interesa-velocidad\" class=\"pivot-outboundlink\" data-vars-post-title=\"Ni muchas series ni muy cerca del fallo: esto debes saber a la hora de entrenar si te interesa la velocidad \"> <img decoding=\"async\" loading=\"lazy\" alt=\"Ni muchas series ni muy cerca del fallo: esto debes saber a la hora de entrenar si te interesa la velocidad \" width=\"375\" height=\"142\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/12\/olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon-2.webp\" onerror=\"this.src=&quot;https:\/\/i.blogs.es\/2afff7\/sam-sabourin-uhkrmvyu470-unsplash-1-\/375_142.jpeg&quot;\"> <\/a> <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p>En &nbsp;Vit\u00f3nica hemos hablado en anteriores ocasiones sobre que <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/buscas-ganar-musculo-basicos-no-mejor-opcion-mejor-alternativa-a-sentadilla-a-banca-al-peso-muerto-1\" data-vars-post-title=\"Si buscas ganar m\u00fasculo los b\u00e1sicos no son la mejor opci\u00f3n: la mejor alternativa a la sentadilla, a la banca y al peso muerto \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/buscas-ganar-musculo-basicos-no-mejor-opcion-mejor-alternativa-a-sentadilla-a-banca-al-peso-muerto-1\">los b\u00e1sicos<\/a> para ganar masa muscular no son la mejor opci\u00f3n por diversas razones:<\/p>\n<ul>\n<li>Involucran muchos grupos musculares y por lo tanto el est\u00edmulo se diluye entre m\u00fasculos que seguramente ni siquiera queremos trabajar.<\/li>\n<li>Suelen ser m\u00e1s inestables por lo que <strong>la producci\u00f3n de fuerza del m\u00fasculo objetivo se reduce<\/strong> (aunque el peso levantado en t\u00e9rminos absolutos en ese movimiento sea elevado).<\/li>\n<li>Generan m\u00e1s <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/no-solo-descanso-estos-tres-gestos-van-a-disminuir-tu-fatiga-central-te-ayudaran-a-ganar-musculo\" data-vars-post-title=\"No es solo el descanso: estos tres gestos van a disminuir tu fatiga central y te ayudar\u00e1n a ganar m\u00e1s m\u00fasculo \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/no-solo-descanso-estos-tres-gestos-van-a-disminuir-tu-fatiga-central-te-ayudaran-a-ganar-musculo\">fatiga<\/a> por lo que dilatan la recuperaci\u00f3n entre sesiones de entrenamiento.<\/li>\n<\/ul>\n<p>No obstante, aqu\u00ed no estamos hablando de ninguna de esas cosas sino de que <strong>la ganancia de fuerza en un b\u00e1sico no hace que ganemos m\u00e1s masa muscular con otros ejercicios de aislamiento<\/strong> que puedan involucrar a los mismos grupos musculares.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.vitonica.com\/entrenamiento\/olvidate-hacer-repeticiones-para-unos-musculos-para-otros-asi-no-funciona-hipertrofia\" class=\"pivot-outboundlink\" data-vars-post-title=\"Olv\u00eddate de hacer m\u00e1s repeticiones para unos m\u00fasculos y menos para otros. As\u00ed no funciona la hipertrofia \"> <img decoding=\"async\" loading=\"lazy\" alt=\"Olv\u00eddate de hacer m\u00e1s repeticiones para unos m\u00fasculos y menos para otros. As\u00ed no funciona la hipertrofia \" width=\"375\" height=\"142\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/12\/olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon-3.webp\" onerror=\"this.src=&quot;https:\/\/i.blogs.es\/c1303a\/kobe-kian-clata-klhbph3r1rc-unsplash-2-\/375_142.jpeg&quot;\"> <\/a> <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p>\u00bfQuiere decir esto que hacer el b\u00e1sico es contraproducente? No.<\/p>\n<p>\u00bfQuiere decir esto que no podemos combinar b\u00e1sicos y de aislamiento? No.<\/p>\n<p>Lo que decimos en este art\u00edculo es que levantar m\u00e1s peso en los ejercicios no implica m\u00e1s hipertrofia porque <strong>la tensi\u00f3n mec\u00e1nica no depende del peso usado sino del esfuerzo al final de una serie<\/strong> y eso puede tener lugar con 50, 100 o 150 kilos.<\/p>\n<p><!-- BREAK 6 --> <\/p>\n<p>En Vit\u00f3nica | <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/esta-forma-disenar-rutinas-entrenamiento-esta-obsoleta-para-ganar-masa-muscular\" data-vars-post-title=\"Esta forma de dise\u00f1ar las rutinas de entrenamiento est\u00e1 obsoleta para ganar masa muscular \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/esta-forma-disenar-rutinas-entrenamiento-esta-obsoleta-para-ganar-masa-muscular\">Esta forma de dise\u00f1ar las rutinas de entrenamiento est\u00e1 obsoleta para ganar masa muscular<\/a><\/p>\n<p>En Vit\u00f3nica | <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/musculacion\/guia-definitiva-para-ganar-masa-muscular-forma-efectiva-todas-claves-que-influiran\" data-vars-post-title=\"La gu\u00eda definitiva para ganar masa muscular de forma efectiva: todas las claves que influir\u00e1n \" data-vars-post-url=\"https:\/\/www.vitonica.com\/musculacion\/guia-definitiva-para-ganar-masa-muscular-forma-efectiva-todas-claves-que-influiran\"><u>C\u00f3mo ganar masa muscular: gu\u00eda completa<\/u><\/a><\/p>\n<p>Im\u00e1genes | <a rel=\"noopener, noreferrer\" href=\"https:\/\/unsplash.com\/es\/@demoya\">Michael DeMoya<\/a>, <a rel=\"noopener, noreferrer\" href=\"https:\/\/unsplash.com\/es\/@gcowie\">Gordon Cowie<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"\n<p> <img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/12\/olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon.jpg\" alt=\"Olv&#x00ED;date&#x20;de&#x20;los&#x20;ejercicios&#x20;b&#x00E1;sicos&#x20;si&#x20;los&#x20;est&#x00E1;s&#x20;incluyendo&#x20;en&#x20;tu&#x20;rutina&#x20;por&#x20;esta&#x20;raz&#x00F3;n&#x20;\"> <\/p>\n<p>Azuzada por el \u00e9xito del powerlifting en los \u00faltimos a\u00f1os existe una creencia que consiste en pensar que hacerse fuerte en los ejercicios b\u00e1sicos (<a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/guia-completa-para-mejorar-sentadilla-como-entrenar-para-levantar-peso\" data-vars-post-title=\"Gu\u00eda completa para mejorar en sentadilla: c\u00f3mo entrenar para levantar m\u00e1s peso \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/guia-completa-para-mejorar-sentadilla-como-entrenar-para-levantar-peso\">sentadilla<\/a>, <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/guia-completa-para-mejorar-ejercicio-fisico-press-banca-asi-puedes-romper-tus-records\" data-vars-post-title=\"Gu\u00eda completa para mejorar en press banca: as\u00ed puedes romper tus r\u00e9cords\" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/guia-completa-para-mejorar-ejercicio-fisico-press-banca-asi-puedes-romper-tus-records\">press de banca<\/a> o <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/guia-completa-para-mejorar-peso-muerto-como-entrenar-para-conseguir-mejor-levantamiento\" data-vars-post-title=\"Gu\u00eda completa para mejorar en peso muerto: c\u00f3mo entrenar para conseguir un mejor levantamiento \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/guia-completa-para-mejorar-peso-muerto-como-entrenar-para-conseguir-mejor-levantamiento\">peso muerto<\/a>) es primordial para aquellos que desean ganar masa muscular, ya sea en amateurs o en culturistas competidores.&nbsp;<\/p>\n<p><!-- BREAK 1 --><\/p>\n<p>Las personas que comulgan con este pensamiento creen que la ganancia de fuerza obtenida en estos ejercicios puede transferirse a otros, generalmente de aislamiento, y que por lo tanto al levantar m\u00e1s peso en estos, esto se traduzca en mayor est\u00edmulo para la hipertrofia.&nbsp;<\/p>\n<p><!-- BREAK 2 --><\/p>\n<p>Dicho esto, en este art\u00edculo <strong>vamos a explicarte qu\u00e9 puedes esperar de los ejercicios b\u00e1sicos si los incluyes en tu rutina de entrenamiento.&nbsp;<\/strong><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.vitonica.com\/entrenamiento\/estabamos-equivocados-ejercicios-basicos-para-ganar-masa-muscular\" class=\"pivot-outboundlink\" data-vars-post-title=\"Est\u00e1bamos equivocados con los ejercicios b\u00e1sicos para ganar masa muscular \"> <img decoding=\"async\" loading=\"lazy\" alt=\"Est&#x00E1;bamos&#x20;equivocados&#x20;con&#x20;los&#x20;ejercicios&#x20;b&#x00E1;sicos&#x20;para&#x20;ganar&#x20;masa&#x20;muscular&#x20;\" width=\"375\" height=\"142\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/12\/olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon.webp\" onerror='this.src=\"https:\/\/i.blogs.es\/6652b0\/danielle-cerullo-oo-rhghlnha-unsplash-3-\/375_142.jpeg\"'> <\/a> <\/div>\n<div class=\"desvio-summary\">\n<div class=\"desvio-taxonomy js-desvio-taxonomy\"> <a href=\"https:\/\/www.vitonica.com\/entrenamiento\/estabamos-equivocados-ejercicios-basicos-para-ganar-masa-muscular\" class=\"desvio-taxonomy-anchor pivot-outboundlink\" data-vars-post-title=\"Est\u00e1bamos equivocados con los ejercicios b\u00e1sicos para ganar masa muscular \">En Vit\u00f3nica<\/a> <\/div>\n<p> <a href=\"https:\/\/www.vitonica.com\/entrenamiento\/estabamos-equivocados-ejercicios-basicos-para-ganar-masa-muscular\" class=\"desvio-title js-desvio-title pivot-outboundlink\" data-vars-post-title=\"Est\u00e1bamos equivocados con los ejercicios b\u00e1sicos para ganar masa muscular \">Est\u00e1bamos equivocados con los ejercicios b\u00e1sicos para ganar masa muscular <\/a> <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<h2>\u00bfSi te haces fuerte en los b\u00e1sicos hipertrofias m\u00e1s con otros ejercicios?<\/h2>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"> <img decoding=\"async\" alt=\"Gordon Cowie Sgrfzxsyrdw Unsplash 7\" class=\"centro_sinmarco\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/12\/olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon-1.webp\"> <\/div>\n<\/div>\n<p>Imaginemos por un instante que somos capaces de levantar en enero 100 kilos en press de banca. Tras unos cuantos meses mejoramos y somos capaces de levantar 125 kilos. Dado que ahora rendimos mejor en banca, \u00bftendr\u00edamos m\u00e1s facilidad para hipertrofiar nuestros <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/consigue-unos-pectorales-fuertes-esta-seleccion-ejercicios\" data-vars-post-title=\"Consigue unos pectorales fuertes con esta selecci\u00f3n de ejercicios \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/consigue-unos-pectorales-fuertes-esta-seleccion-ejercicios\">pectorales<\/a>, <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/seleccion-ejercicios-que-tienes-que-tener-cuenta-para-fortalecer-entrenar-triceps\" data-vars-post-title=\"La selecci\u00f3n de ejercicios que tienes que tener en cuenta para fortalecer y entrenar los tr\u00edceps \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/seleccion-ejercicios-que-tienes-que-tener-cuenta-para-fortalecer-entrenar-triceps\">tr\u00edceps<\/a> o <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/seleccion-ejercicios-que-necesitas-para-trabajar-deltoides\" data-vars-post-title=\"La selecci\u00f3n de ejercicios que necesitas para trabajar los deltoides \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/seleccion-ejercicios-que-necesitas-para-trabajar-deltoides\">deltoides anteriores<\/a> al poder, presuntamente, levantar m\u00e1s peso en otros ejercicios?<\/p>\n<p><!-- BREAK 3 --><\/p>\n<p>Planteamos esto porque existe una creencia que defiende que la fuerza ganada en ejercicios b\u00e1sicos se puede transferir a otros ejercicios, de aislamiento por lo general, y que por lo tanto al levantar m\u00e1s peso en estos el est\u00edmulo para hipertrofia es mayor. Veamos por qu\u00e9 esto no es as\u00ed.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<ul>\n<li>En primer lugar, <strong>la fuerza es espec\u00edfica<\/strong>, es decir, si hacemos press de banca mejoramos en press de banca. Esta pr\u00e1ctica de la banca puede hacer que ganemos masa muscular o que mejoremos la activaci\u00f3n voluntaria de las fibras de nuestro pectoral y que esto se pueda transferir a otros ejercicios similares, pero <strong>realmente podr\u00eda pasar con cualquier otro ejercicio, no solo con la banca.<\/strong><\/li>\n<li>En segundo lugar, aunque la fuerza ganada en press de banca implicara que pudi\u00e9ramos hacer, por ejemplo, cruce de poleas con m\u00e1s peso, esto no se traduce en m\u00e1s hipertrofia porque el est\u00edmulo de hipertrofia no depende del peso usado sino del esfuerzo creciente hacia el final de una serie y de la <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/importancia-ultimas-repeticiones-durante-serie-cuando-buscamos-hipertrofia\" data-vars-post-title=\"Si buscas conseguir hipertrofia, presta especial atenci\u00f3n a las \u00faltimas repeticiones: la clave est\u00e1 en la relaci\u00f3n fuerza-velocidad\" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/importancia-ultimas-repeticiones-durante-serie-cuando-buscamos-hipertrofia\">p\u00e9rdida en la velocidad de acortamiento<\/a> de nuestras fibras musculares.<\/li>\n<\/ul>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.vitonica.com\/entrenamiento\/muchas-series-muy-cerca-fallo-esto-debes-saber-a-hora-entrenar-te-interesa-velocidad\" class=\"pivot-outboundlink\" data-vars-post-title=\"Ni muchas series ni muy cerca del fallo: esto debes saber a la hora de entrenar si te interesa la velocidad \"> <img decoding=\"async\" loading=\"lazy\" alt=\"Ni&#x20;muchas&#x20;series&#x20;ni&#x20;muy&#x20;cerca&#x20;del&#x20;fallo&#x3A;&#x20;esto&#x20;debes&#x20;saber&#x20;a&#x20;la&#x20;hora&#x20;de&#x20;entrenar&#x20;si&#x20;te&#x20;interesa&#x20;la&#x20;velocidad&#x20;&#x20;\" width=\"375\" height=\"142\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/12\/olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon-2.webp\" onerror='this.src=\"https:\/\/i.blogs.es\/2afff7\/sam-sabourin-uhkrmvyu470-unsplash-1-\/375_142.jpeg\"'> <\/a> <\/div>\n<div class=\"desvio-summary\">\n<div class=\"desvio-taxonomy js-desvio-taxonomy\"> <a href=\"https:\/\/www.vitonica.com\/entrenamiento\/muchas-series-muy-cerca-fallo-esto-debes-saber-a-hora-entrenar-te-interesa-velocidad\" class=\"desvio-taxonomy-anchor pivot-outboundlink\" data-vars-post-title=\"Ni muchas series ni muy cerca del fallo: esto debes saber a la hora de entrenar si te interesa la velocidad \">En Vit\u00f3nica<\/a> <\/div>\n<p> <a href=\"https:\/\/www.vitonica.com\/entrenamiento\/muchas-series-muy-cerca-fallo-esto-debes-saber-a-hora-entrenar-te-interesa-velocidad\" class=\"desvio-title js-desvio-title pivot-outboundlink\" data-vars-post-title=\"Ni muchas series ni muy cerca del fallo: esto debes saber a la hora de entrenar si te interesa la velocidad \">Ni muchas series ni muy cerca del fallo: esto debes saber a la hora de entrenar si te interesa la velocidad <\/a> <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p>En &nbsp;Vit\u00f3nica hemos hablado en anteriores ocasiones sobre que <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/buscas-ganar-musculo-basicos-no-mejor-opcion-mejor-alternativa-a-sentadilla-a-banca-al-peso-muerto-1\" data-vars-post-title=\"Si buscas ganar m\u00fasculo los b\u00e1sicos no son la mejor opci\u00f3n: la mejor alternativa a la sentadilla, a la banca y al peso muerto \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/buscas-ganar-musculo-basicos-no-mejor-opcion-mejor-alternativa-a-sentadilla-a-banca-al-peso-muerto-1\">los b\u00e1sicos<\/a> para ganar masa muscular no son la mejor opci\u00f3n por diversas razones:<\/p>\n<ul>\n<li>Involucran muchos grupos musculares y por lo tanto el est\u00edmulo se diluye entre m\u00fasculos que seguramente ni siquiera queremos trabajar.<\/li>\n<li>Suelen ser m\u00e1s inestables por lo que <strong>la producci\u00f3n de fuerza del m\u00fasculo objetivo se reduce<\/strong> (aunque el peso levantado en t\u00e9rminos absolutos en ese movimiento sea elevado).<\/li>\n<li>Generan m\u00e1s <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/no-solo-descanso-estos-tres-gestos-van-a-disminuir-tu-fatiga-central-te-ayudaran-a-ganar-musculo\" data-vars-post-title=\"No es solo el descanso: estos tres gestos van a disminuir tu fatiga central y te ayudar\u00e1n a ganar m\u00e1s m\u00fasculo \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/no-solo-descanso-estos-tres-gestos-van-a-disminuir-tu-fatiga-central-te-ayudaran-a-ganar-musculo\">fatiga<\/a> por lo que dilatan la recuperaci\u00f3n entre sesiones de entrenamiento.<\/li>\n<\/ul>\n<p>No obstante, aqu\u00ed no estamos hablando de ninguna de esas cosas sino de que <strong>la ganancia de fuerza en un b\u00e1sico no hace que ganemos m\u00e1s masa muscular con otros ejercicios de aislamiento<\/strong> que puedan involucrar a los mismos grupos musculares.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.vitonica.com\/entrenamiento\/olvidate-hacer-repeticiones-para-unos-musculos-para-otros-asi-no-funciona-hipertrofia\" class=\"pivot-outboundlink\" data-vars-post-title=\"Olv\u00eddate de hacer m\u00e1s repeticiones para unos m\u00fasculos y menos para otros. As\u00ed no funciona la hipertrofia \"> <img decoding=\"async\" loading=\"lazy\" alt=\"Olv&#x00ED;date&#x20;de&#x20;hacer&#x20;m&#x00E1;s&#x20;repeticiones&#x20;para&#x20;unos&#x20;m&#x00FA;sculos&#x20;y&#x20;menos&#x20;para&#x20;otros.&#x20;As&#x00ED;&#x20;no&#x20;funciona&#x20;la&#x20;hipertrofia&#x20;&#x20;\" width=\"375\" height=\"142\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/12\/olvidate-de-los-ejercicios-basicos-si-los-estas-incluyendo-en-tu-rutina-por-esta-razon-3.webp\" onerror='this.src=\"https:\/\/i.blogs.es\/c1303a\/kobe-kian-clata-klhbph3r1rc-unsplash-2-\/375_142.jpeg\"'> <\/a> <\/div>\n<div class=\"desvio-summary\">\n<div class=\"desvio-taxonomy js-desvio-taxonomy\"> <a href=\"https:\/\/www.vitonica.com\/entrenamiento\/olvidate-hacer-repeticiones-para-unos-musculos-para-otros-asi-no-funciona-hipertrofia\" class=\"desvio-taxonomy-anchor pivot-outboundlink\" data-vars-post-title=\"Olv\u00eddate de hacer m\u00e1s repeticiones para unos m\u00fasculos y menos para otros. As\u00ed no funciona la hipertrofia \">En Vit\u00f3nica<\/a> <\/div>\n<p> <a href=\"https:\/\/www.vitonica.com\/entrenamiento\/olvidate-hacer-repeticiones-para-unos-musculos-para-otros-asi-no-funciona-hipertrofia\" class=\"desvio-title js-desvio-title pivot-outboundlink\" data-vars-post-title=\"Olv\u00eddate de hacer m\u00e1s repeticiones para unos m\u00fasculos y menos para otros. As\u00ed no funciona la hipertrofia \">Olv\u00eddate de hacer m\u00e1s repeticiones para unos m\u00fasculos y menos para otros. As\u00ed no funciona la hipertrofia <\/a> <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p>\u00bfQuiere decir esto que hacer el b\u00e1sico es contraproducente? No.<\/p>\n<p>\u00bfQuiere decir esto que no podemos combinar b\u00e1sicos y de aislamiento? No.<\/p>\n<p>Lo que decimos en este art\u00edculo es que levantar m\u00e1s peso en los ejercicios no implica m\u00e1s hipertrofia porque <strong>la tensi\u00f3n mec\u00e1nica no depende del peso usado sino del esfuerzo al final de una serie<\/strong> y eso puede tener lugar con 50, 100 o 150 kilos.<\/p>\n<p><!-- BREAK 6 --><\/p>\n<p>En Vit\u00f3nica | <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/entrenamiento\/esta-forma-disenar-rutinas-entrenamiento-esta-obsoleta-para-ganar-masa-muscular\" data-vars-post-title=\"Esta forma de dise\u00f1ar las rutinas de entrenamiento est\u00e1 obsoleta para ganar masa muscular \" data-vars-post-url=\"https:\/\/www.vitonica.com\/entrenamiento\/esta-forma-disenar-rutinas-entrenamiento-esta-obsoleta-para-ganar-masa-muscular\">Esta forma de dise\u00f1ar las rutinas de entrenamiento est\u00e1 obsoleta para ganar masa muscular<\/a><\/p>\n<p>En Vit\u00f3nica | <a class=\"text-outboundlink\" href=\"https:\/\/www.vitonica.com\/musculacion\/guia-definitiva-para-ganar-masa-muscular-forma-efectiva-todas-claves-que-influiran\" data-vars-post-title=\"La gu\u00eda definitiva para ganar masa muscular de forma efectiva: todas las claves que influir\u00e1n \" data-vars-post-url=\"https:\/\/www.vitonica.com\/musculacion\/guia-definitiva-para-ganar-masa-muscular-forma-efectiva-todas-claves-que-influiran\"><u>C\u00f3mo ganar masa muscular: gu\u00eda completa<\/u><\/a><\/p>\n<p>Im\u00e1genes | <a rel=\"noopener, noreferrer\" href=\"https:\/\/unsplash.com\/es\/@demoya\">Michael DeMoya<\/a>, <a rel=\"noopener, noreferrer\" href=\"https:\/\/unsplash.com\/es\/@gcowie\">Gordon Cowie<\/a><\/p>\n<p><script> (function() { window._JS_MODULES = window._JS_MODULES || {}; var headElement = document.getElementsByTagName('head')[0]; if (_JS_MODULES.instagram) { var instagramScript = document.createElement('script'); instagramScript.src = 'https:\/\/platform.instagram.com\/en_US\/embeds.js'; instagramScript.async = true; instagramScript.defer = true; headElement.appendChild(instagramScript); } })();\n<\/script> <\/p>\n<p> &#8211; <br \/> La noticia <a href=\"https:\/\/www.vitonica.com\/entrenamiento\/olvidate-ejercicios-basicos-estas-incluyendo-tu-rutina-esta-razon&#x3F;utm_source&#x3D;feedburner&amp;utm_medium&#x3D;feed&amp;utm_campaign&#x3D;29_Dec_2024\"> <em> Olv\u00eddate de los ejercicios b\u00e1sicos si los est\u00e1s incluyendo en tu rutina por esta raz\u00f3n <\/em> <\/a> fue publicada originalmente en <a href=\"https:\/\/www.vitonica.com&#x3F;utm_source&#x3D;feedburner&amp;utm_medium&#x3D;feed&amp;utm_campaign&#x3D;29_Dec_2024\"> <strong> Vit\u00f3nica <\/strong> <\/a> por <a href=\"https:\/\/www.vitonica.com\/autor\/angel-gardachal&#x3F;utm_source&#x3D;feedburner&amp;utm_medium&#x3D;feed&amp;utm_campaign&#x3D;29_Dec_2024\"> \u00c1ngel Gardachal <\/a> . <\/p>\n","protected":false},"author":1,"featured_media":30339,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/30338"}],"collection":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/comments?post=30338"}],"version-history":[{"count":0,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/30338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media\/30339"}],"wp:attachment":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media?parent=30338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/categories?post=30338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/tags?post=30338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}