{"id":29117,"date":"2024-11-10T11:41:00","date_gmt":"2024-11-10T11:41:00","guid":{"rendered":"https:\/\/www.iprofesional.com\/economia\/416854-pagar-con-dolar-y-ahorrar-en-pesos-se-cumple-sueno-de-luis-caputo"},"modified":"2024-11-10T11:41:00","modified_gmt":"2024-11-10T11:41:00","slug":"con-el-blue-en-baja-pagar-con-dolares-del-colchon-como-pronosticaba-luis-caputo","status":"publish","type":"post","link":"https:\/\/latecordoba.com\/index.php\/2024\/11\/10\/con-el-blue-en-baja-pagar-con-dolares-del-colchon-como-pronosticaba-luis-caputo\/","title":{"rendered":"Con el blue en baja, pagar con d\u00f3lares del colch\u00f3n, como pronosticaba Luis Caputo"},"content":{"rendered":"\n<div class=\"media_block\"><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/11\/con-el-blue-en-baja-pagar-con-dolares-del-colchon-como-pronosticaba-luis-caputo.jpg\"><\/div>\n<div><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/11\/con-el-blue-en-baja-pagar-con-dolares-del-colchon-como-pronosticaba-luis-caputo.webp\" class=\"ff-og-image-inserted\"><\/div>\n<p><span>Al final, aquella <strong>profec\u00eda de Luis Caputo,<\/strong> que dec\u00eda <a href=\"https:\/\/www.iprofesional.com\/economia\/412871-luis-caputo-lista-pronosticos-sobre-peso-dolar-inflacion-salarios\" target=\"_blank\" rel=\"noopener noreferrer\">que el peso iba a empezar a ser la moneda escasa y que la gente iba a hacer circular los d\u00f3lares<\/a>, ya no parece tan alocada y algunos sectores empiezan a ver s\u00edntomas de la famosa <strong>&#8220;dolarizaci\u00f3n end\u00f3gena&#8221;.<\/strong><\/span>\n<\/p>\n<p><span>Por lo pronto, en las agencias de viajes y turismo,<strong> el p\u00fablico minorista ya usa d\u00f3lares &#8220;del colch\u00f3n&#8221; para pagar<\/strong>, porque resulta mucho m\u00e1s barato que sacar la tarjeta y financiar sus viajes en pesos. Y se trata de un sector que ha llegado a registrar salidas netas de d\u00f3lares por m\u00e1s de u$s8.000 millones al a\u00f1o.<\/span>\n<\/p>\n<p><span>&#8220;En este momento, <a href=\"https:\/\/www.iprofesional.com\/economia\/416053-antes-de-planificar-viaje-al-exterior-que-pasara-con-dolar-turista\" target=\"_blank\" rel=\"noopener noreferrer\">el 80% de los clientes de las agencias vienen con los d\u00f3lares en la mano<\/a>. Casi que los \u00fanicos que emiten pasajes en pesos son los del sector corporativo&#8221;<\/span>, afirma un directivo de agencia.\n<\/p>\n<p>Es claro por qu\u00e9 ocurre ese fen\u00f3meno:<strong> llevar d\u00f3lares cuesta $1.135 <\/strong>en el mercado blue, mientras que pagar un pasaje de avi\u00f3n en pesos<strong> usando tarjeta implica un tipo de cambio de $1.626<\/strong> -que surge de aplicar el 30% del impuesto PAIS m\u00e1s la percepci\u00f3n de otro 30% por el impuesto a las Ganancias-.\n<\/p>\n<p>La situaci\u00f3n <strong>es funcional al Banco Central<\/strong>, que as\u00ed sacrifica menos reservas. Por cierto que esta carga impositiva para el turismo no es un invento del gobierno de Milei; m\u00e1s bien al contrario, lo que est\u00e1 ocurriendo ahora era algo que hab\u00edan buscado obstinadamente por los funcionarios del gobierno anterior, que fueron progresivamente poniendo obst\u00e1culos a la financiaci\u00f3n en pesos. \u00bfPor qu\u00e9 los viajeros pagaban antes en pesos y ahora lo hace en d\u00f3lares? <span>La gran diferencia es el nivel del d\u00f3lar paralelo, que ahora est\u00e1 en niveles m\u00ednimos.<\/span>\n<\/p>\n<p>Hay ejemplos en otros rubros, como acaban de comprobar los miles de consumidores que <a href=\"https:\/\/www.iprofesional.com\/economia\/416828-exito-o-fracaso-cuanto-facturo-ventas-durante-cybermonday-2024\" target=\"_blank\" rel=\"noopener noreferrer\">batieron r\u00e9cords de compras en la \u00faltima edici\u00f3n del CyberMonday<\/a>. El evento de comercio electr\u00f3nico gener\u00f3<strong> un volumen de $490.000 millones<\/strong>, y buena parte de esas transacciones fueron<strong> pagadas directamente en d\u00f3lares<\/strong>.\n<\/p>\n<p>Para evitar los altos costos de lo recargos con tarjeta, <strong>se masific\u00f3 la compra de d\u00f3lar en el mercado MEP<\/strong>, lo cual permite cancelar las compras de bienes y servicios facturados en d\u00f3lares, desde una propia cuenta dolarizada.\n<\/p>\n<p>Y hay otras actividades que est\u00e1n en recuperaci\u00f3n, en las que t\u00edpicamente se usa el d\u00f3lar como &#8220;lubricante&#8221; de la actividad. La <strong>construcci\u00f3n, en particular las refacciones y peque\u00f1as obras<\/strong> son el ejemplo cl\u00e1sico. Y el propio Caputo festej\u00f3 en las redes sociales el hecho de que en septiembre se haya registrado <strong>un incremento mensual de 2,4%<\/strong>.\n<\/p>\n<p><span>En estos casos, un d\u00f3lar paralelo cuya cotizaci\u00f3n cae act\u00faa como aliciente para que los ahorristas se desprendan de los billetes &#8220;del colch\u00f3n&#8221;, ante el temor de una mayor desvalorizaci\u00f3n.<\/span>\n<\/p>\n<p>No necesariamente significa que est\u00e9n haciendo un buen negocio: obviamente, es mucho mejor vender d\u00f3lares para construir cuando la brecha del blue es mayor <span>-hubo momentos en que se pod\u00eda construir un metro cuadrado por u$s800, mientras hoy cuesta u$s1.300-<\/span>. Pero todo se reduce a una<strong> cuesti\u00f3n de expectativa: <\/strong>si la gente cree que el blue seguir\u00e1 en su lugar -o que seguir\u00e1 cayendo-, entonces estar\u00e1 m\u00e1s dispuesta a <strong>concretar su inversi\u00f3n en vez de atesorar<\/strong> los billetes con la cara de Benjam\u00edn Franklin.\n<\/p>\n<p>Y este es, precisamente, uno de esos momentos. A pesar de las cr\u00edticas que recibe el plan econ\u00f3mico del gobierno -y a pesar de que en los pa\u00edses vecinos se est\u00e1n devaluando las monedas-, hay una relativa confianza sobre la continuidad de la estabilidad cambiaria.\n<\/p>\n<h2>D\u00f3lar proveniente del blanqueo, soja y carry trade<\/h2>\n<p>Varios motivos confluyen para ello. Uno es potente pero de corta duraci\u00f3n: <a href=\"https:\/\/www.iprofesional.com\/impuestos\/416797-blanqueo-dinero-efectivo-con-ingresos-de-ultimo-momento\" target=\"_blank\" rel=\"noopener noreferrer\">el blanqueo de capitales<\/a>, que inyect\u00f3 u$s22.400 millones, seg\u00fan inform\u00f3 el propio Caputo. Y hay estimaciones de que esa cifra podr\u00eda agrandarse, con la inclusi\u00f3n de otros bienes.\n<\/p>\n<p>El otro motivo es menor en monto pero ayudar\u00e1 a atravesar todo el verano:<strong> un flujo comercial positivo,<\/strong> gracias a que los productores agr\u00edcolas, aun dejando ver su malhumor por las retenciones, contin\u00faan vendiendo a buen ritmo. <span>Se estima que todav\u00eda quedan guardados -de la \u00faltima cosecha- 20 millones de toneladas de soja, 14 millones de toneladas de ma\u00edz y 19 millones de toneladas de trigo.<\/span>\n<\/p>\n<p>Esto implica que, en las c\u00e9lebres silobolsas, hay mercader\u00eda por un valor superior a los u$s13.000 millones. Una cifra m\u00e1s que razonable como para que el gobierno siga reforzando las reservas del BCRA y resista presiones devaluatorias hasta que, en abril pr\u00f3ximo, empiece la llegada de los d\u00f3lares provenientes de la cosecha gruesa -para la cual se espera que el campo aporte <strong>otras 55 millones de toneladas de soja<\/strong>-.\n<\/p>\n<p>\u00bfPor qu\u00e9 los productores est\u00e1n vendiendo ahora, con un precio internacional deprimido y altos impuestos internos? Otra vez, la respuesta est\u00e1 en <strong>la m\u00ednima brecha<\/strong> existente entre el d\u00f3lar paralelo y el tipo de cambio oficial. Cuando esa brecha se achica, mayor es el porcentaje del precio internacional que capta el exportador.<span> Actualmente, lo que captan los sojeros es un 59% -el m\u00e1ximo posible es 67%, dado que las retenciones le sacan al productor un 33% del valor-. En los programas de incentivo de <strong>Sergio Massa <\/strong>se llegaba a un 50%, mientras que en los peores momentos de la gesti\u00f3n de<strong> Alberto Fern\u00e1ndez <\/strong>apenas pod\u00edan captar un 30%.<\/span>\n<\/p>\n<p>Finalmente, hay otro factor fundamental: la estabilidad cambiaria hace que, para los inversores resulte m\u00e1s rentable deshacerse de los d\u00f3lares y buscar una ganancia de tasa -el <em>&#8220;carry trade&#8221;,<\/em> en la jerga-, lo cual ayuda a la caja del Banco Central y retroalimenta la sensaci\u00f3n de calma con el d\u00f3lar.\n<\/p>\n<h2>Circulan los d\u00f3lares que estaban en el colch\u00f3n, como quer\u00eda Luis Caputo<\/h2>\n<p>En definitiva, y parafraseando a Pepe Mujica, hoy se da el extra\u00f1o caso de que Argentina<strong> est\u00e1 &#8220;embuchada de d\u00f3lares&#8221;.<\/strong> Tanto que empieza a ser un problema para los bancos el encontrarle <strong>un destino rentable a los u$s34.578 millones que quedaron depositados<\/strong>.\n<\/p>\n<p>En los \u00faltimos d\u00edas, se volvi\u00f3 a notar, igual que a inicios de octubre, un movimiento de salida de esos dep\u00f3sitos. Se trata de &#8220;blanqueadores&#8221; que, una vez cumplido su cometido, prefieren tener los d\u00f3lares en la mano, sea para volver a atesorar o para hacer pagos en efectivo.\n<\/p>\n<p><span>Pero lo cierto es que el grueso de ese dinero sigue en el sistema bancario. <\/span>Resulta m\u00e1s barato hoy tomar un cr\u00e9dito en d\u00f3lares que en pesos, pero hay que cumplir con el requisito de generar ingresos en divisas -una regulaci\u00f3n que se impuso para evitar el tr\u00e1gico &#8220;<strong>descalce&#8221; de monedas<\/strong> que se gener\u00f3 con el fin de la convertibilidad en 2002-.\n<\/p>\n<p>Hay consultores, sin embargo, que est\u00e1n recomendando a sus clientes<strong> v\u00edas indirectas de financiarse en d\u00f3lares <\/strong>para aprovechar la oportunidad. Por caso, <strong>Salvador Di Stefano<\/strong>, muy escuchado entre los empresarios agr\u00edcolas, sugiere la emisi\u00f3n de pagar\u00e9s en d\u00f3lares con garant\u00eda de una Sociedad de Garant\u00eda Rec\u00edproca.\n<\/p>\n<p><span>&#8220;El empresario se puede financiar en el mercado de capitales, a la tasa que m\u00e1s le sea conveniente. Si tiene ahorros en bonos y acciones, puede ponerlos como garant\u00eda para financiarse al 40% en pesos o al 2% en d\u00f3lares&#8221;<\/span>, argumenta.\n<\/p>\n<p>Y agrega que la peor decisi\u00f3n econ\u00f3mica, en este momento, es quedarse con d\u00f3lares en la mano, porque la cotizaci\u00f3n tiende a <strong>seguir bajando hasta la zona de $1.015<\/strong>. Su recomendaci\u00f3n es <strong>usar los d\u00f3lares para transacciones <\/strong>en vez de venderlos para hacerse de pesos. En otras palabras, lo contrario a lo que se ha hecho tradicionalmente.\n<\/p>\n<p>Su argumento es que se est\u00e1 entrando en una \u00e9poca del a\u00f1o con mayor necesidad de pesos en la econom\u00eda y que las empresas que no est\u00e1n dispuestas pagar altas tasas en pesos <strong>se financiar\u00e1n con capital propio<\/strong>, vendiendo los d\u00f3lares que ten\u00edan guardados.\n<\/p>\n<p><span>&#8220;La oferta de d\u00f3lares con una demanda inexistente nos lleva a que el precio del d\u00f3lar arbitre a la baja. Si a esto le sumamos que hay una venta masiva de d\u00f3lares que vienen del blanqueo, para transformar esos billetes en bienes registrables, casi que no tenemos piso para el d\u00f3lar&#8221;<\/span>, se\u00f1ala.\n<\/p>\n<h2>Menos pesos, m\u00e1s d\u00f3lares: el dato que destaca el Gobierno<\/h2>\n<p><span>De momento, los indicadores parecen darle la raz\u00f3n: la gente quiere tener m\u00e1s pesos. El <strong>informe monetario del Banco Central<\/strong> marca que en octubre la demanda de pesos aument\u00f3 su velocidad. El indicador M3 -que mide la base monetaria amplia- <strong>creci\u00f3 un 3% real en un mes<\/strong>.&nbsp;<span>&nbsp;Y los cr\u00e9ditos en pesos al sector privado tambi\u00e9n vienen creciendo fuerte: un 6,3% real en octubre.<\/span><\/span>\n<\/p>\n<p><span>En t\u00e9rminos de PBI, esa base monetaria amplia est\u00e1 en 11,4%, lo cual todav\u00eda la ubica por debajo del nivel de hace un a\u00f1o.<\/span>\n<\/p>\n<p><span>El dato que destaca el gobierno es que ese aumento en la demanda de pesos ocurre en un contexto de inflaci\u00f3n en baja, recuperaci\u00f3n de la actividad econ\u00f3mica y un flujo positivo de ingreso de d\u00f3lares.<\/span>\n<\/p>\n<p><span>Es decir, condiciones que se acercan a las que el propio <strong>Javier Milei<\/strong> hab\u00eda identificado como las necesarias para el levantamiento del cepo. <\/span>\n<\/p>\n<p>En el corto plazo, los analistas tienden a pensar que la estrategia podr\u00eda salir bien, aunque manifiestan sus dudas sobre hasta d\u00f3nde ayudar\u00e1 el contexto externo.\n<\/p>\n<p>Un reporte de la<strong> consultora&nbsp; LCG<\/strong> observa: &#8220;El gobierno, neg\u00e1ndose a tener tasas positivas y confiado en que las expectativas cambiarias se mantendr\u00e1n estables, acompa\u00f1\u00f3 este probable descenso de la inflaci\u00f3n con una reducci\u00f3n en las tasas de inter\u00e9s (la de pol\u00edtica monetaria pas\u00f3 de 40% a 35% anual), con la idea de que ser\u00e1n otros factores los que ayuden a bajar el incremento de precios hacia valores m\u00e1s bajos&#8221;. Pero recuerda que<a href=\"https:\/\/www.iprofesional.com\/economia\/416672-riesgo-para-argentina-que-pasa-con-dolar-en-la-region-por-efecto-donald-trump\" target=\"_blank\" rel=\"noopener noreferrer\"> la situaci\u00f3n de Estados Unidos podr\u00eda volverse en contra.<\/a><span><\/span>\n<\/p>\n<h2><span>\u00bfCu\u00e1nto durar\u00e1n estos buenos resultados para el Gobierno?<\/span><\/h2>\n<p><span>Como siempre, la pregunta es<strong> si todo se trata apenas de un fen\u00f3meno pasajero<\/strong> o si la econom\u00eda est\u00e1 en un cambio de paradigma.<\/span>\n<\/p>\n<p><span><span>Por lo pronto, hasta los economistas m\u00e1s cr\u00edticos ven chances de que la bonanza se prolongue<\/span>. <strong>Marina Dal Poggetto<\/strong>, que suele poner la lupa en las dificultades para acumular reservas en el BCRA, explic\u00f3 este punto.<\/span>\n<\/p>\n<p><span>&#8220;Si este escenario se extiende, se dar\u00eda la situaci\u00f3n de que <a href=\"https:\/\/www.iprofesional.com\/economia\/416110-marina-dal-poggetto-no-pega-una-y-el-viceministro-de-economia-se-lo-recuerda\" target=\"_blank\" rel=\"noopener noreferrer\">es el financiamiento en d\u00f3lares al sector privado el que financiar\u00eda en forma indirecta el aumento de las importaciones<\/a>, un aumento derivado del intento de impulsar el consumo v\u00eda cr\u00e9dito dom\u00e9stico con un d\u00f3lar atrasado&#8221;, argument\u00f3 la directora de Eco Go. <\/span>\n<\/p>\n<p><span>Y dijo flotando el punto que es objeto de debate en este momento: si se mantendr\u00e1 o no el flujo de d\u00f3lares ingresando al pa\u00eds. Es una discusi\u00f3n que<strong> se exacerb\u00f3 despu\u00e9s del triunfo de Donald Trump en Estados Unidos,<\/strong> porque mientras algunos ven all\u00ed una llave para destrabar la llegada de d\u00f3lares del FMI, <strong>otros ven una huida de inversores<\/strong> que se refugiar\u00e1n en el d\u00f3lar y, para colmo, una ca\u00edda en los precios de materias primas.<\/span>\n<\/p>\n<p><span><span>Lo cierto es que, por ahora, Toto Caputo festeja su momento: las cosas est\u00e1n saliendo tal como \u00e9l las hab\u00eda predicho.<\/span> Los pesos empiezan a escasear y sube la tasa crediticia mientras el d\u00f3lar empieza a verse en algunos sectores como moneda de transacci\u00f3n. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"\n<div class=\"media_block\"><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/11\/con-el-blue-en-baja-pagar-con-dolares-del-colchon-como-pronosticaba-luis-caputo.jpg\"><\/div>\n<p> Cada vez m\u00e1s ramas de la actividad ven el uso de d\u00f3lares como forma de pago, ante la estabilidad cambiaria. Los analistas debaten hasta cu\u00e1ndo puede durar <iframe width=\"0\" height=\"0\" border=\"0\"> <script> (function(i,s,o,g,r,a,m){i['GoogleAnalyticsObject']=r;i[r]=i[r]||function(){ (i[r].q=i[r].q||[]).push(arguments)},i[r].l=1*new Date();a=s.createElement(o), m=s.getElementsByTagName(o)[0];a.async=1;a.src=g;m.parentNode.insertBefore(a,m) })(window,document,'script','https:\/\/www.google-analytics.com\/analytics.js','ga'); ga('create', 'GTM-5LW5KQD', 'auto'); ga('require', 'displayfeatures'); ga('set', 'campaignSource', 'RSS Client for iProfesional'); ga('set', 'campaignMedium', 'RSS Client for iProfesional'); ga('set', {\"dataSource\": \"rss.atom.iprofesional.com\"}); ga('set', {\"referrer\": \"rss.atom.iprofesional.com\"}); ga('set', 'title', 'RSS Client for iProfesional'); ga('send', 'pageview'); <\/script> <!-- Begin comScore Tag --> <script> var _comscore = _comscore || []; _comscore.push({ c1: \"2\", c2: \"16597048\" }); (function() { var s = document.createElement(\"script\"), el = document.getElementsByTagName(\"script\")[0]; s.async = true; s.src = \"https:\/\/sb.scorecardresearch.com\/cs\/16597048\/beacon.js\"; el.parentNode.insertBefore(s, el); })(); <\/script> <noscript> <img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/11\/con-el-blue-en-baja-pagar-con-dolares-del-colchon-como-pronosticaba-luis-caputo.gif\"> <\/noscript> <!-- End comScore Tag --> <\/iframe> <iframe border=\"0px\" style=\"display: none\" width=0 height=0 src=\"https:\/\/www.iprofesional.com\/ga4.html?gtag_id=G-N13KWJP8BK&amp;title=Con el blue en baja, pagar con d\u00f3lares del colch\u00f3n, como pronosticaba Luis Caputo&amp;location=https:\/\/www.iprofesional.com\/economia\/416854-pagar-con-dolar-y-ahorrar-en-pesos-se-cumple-sueno-de-luis-caputo&amp;referrer=rss.atom.iprofesional.com&amp;ci=RSS Client for iProfesional&amp;cs=RSS Client for iProfesional&amp;cm=RSS&amp;cn=RSS Client for iProfesional&amp;cc=RSS Client for iProfesional\"><\/iframe>  <\/p>\n","protected":false},"author":1,"featured_media":29118,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/29117"}],"collection":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/comments?post=29117"}],"version-history":[{"count":0,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/29117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media\/29118"}],"wp:attachment":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media?parent=29117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/categories?post=29117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/tags?post=29117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}