{"id":29098,"date":"2024-11-09T10:20:00","date_gmt":"2024-11-09T10:20:00","guid":{"rendered":"https:\/\/www.iprofesional.com\/tecnologia\/416793-celulares-samsung-y-motorola-ante-los-competidores-chinos"},"modified":"2024-11-09T10:20:00","modified_gmt":"2024-11-09T10:20:00","slug":"samsung-y-motorola-revelan-sus-armas-contra-los-nuevos-competidores-chinos","status":"publish","type":"post","link":"https:\/\/latecordoba.com\/index.php\/2024\/11\/09\/samsung-y-motorola-revelan-sus-armas-contra-los-nuevos-competidores-chinos\/","title":{"rendered":"Samsung y Motorola revelan sus armas contra los nuevos competidores chinos"},"content":{"rendered":"\n<div class=\"media_block\"><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/11\/samsung-y-motorola-revelan-sus-armas-contra-los-nuevos-competidores-chinos.jpg\"><\/div>\n<div><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/11\/samsung-y-motorola-revelan-sus-armas-contra-los-nuevos-competidores-chinos.webp\" class=\"ff-og-image-inserted\"><\/div>\n<p>El mercado argentinos de <strong><a href=\"https:\/\/www.iprofesional.com\/tecnologia\/415787-llegan-nuevas-marcas-celulares-argentina-competirle-samsung\" target=\"_blank\" title=\"Nuevas marcas de celulares llegan a la Argentina\" rel=\"noopener noreferrer\">celulares<\/a> <\/strong>recibi\u00f3 en el 2024 la constituye a la mayor\u00eda de las grandes marcas chinas, que desembarcaron como si fueran un pelot\u00f3n para la conquista.\n<\/p>\n<p><strong>Xiaomi y TCL <\/strong>hab\u00edan plantado la cabecera de playa hace algunos a\u00f1os, pero este a\u00f1o ZTE multiplic\u00f3 su pisada local con su marca de gama media y alta Nubia. Tambi\u00e9n llegaron Transsion, con dos de sus marcas: Tecno Mobile e Infinix, y BBK Electronics con una de sus firmas, Oppo.\n<\/p>\n<p>Todas estas compa\u00f1\u00edas provenientes de China encararon su aterrizaje local de la mano de socios locales que se encargan de la producci\u00f3n de los <a href=\"https:\/\/www.iprofesional.com\/tecnologia\/405770-que-celulares-comprar-mas-alla-samsung-y-motorola\" target=\"_blank\" title=\"Celulares m\u00e1s all\u00e1 de Samsung y Motorola\" rel=\"noopener noreferrer\">celulares<\/a> en la provincia de&nbsp;<strong>Tierra del Fuego<\/strong>.\n<\/p>\n<p>Estos movimientos son seguidos de cerca por dos empresas que est\u00e1n presentes en el mercado local y que en conjunto ostentan m\u00e1s del 80% de las ventas en el pa\u00eds: <strong>Samsung y Motorola<\/strong>.\n<\/p>\n<p>\u00bfC\u00f3mo se preparan estas compa\u00f1\u00edas para enfrentar una competencia m\u00e1s variada? iProfesional consult\u00f3 a dos altos ejecutivos de sus oficinas locales.\n<\/p>\n<h2>Un a\u00f1o de transici\u00f3n para Samsung<\/h2>\n<p><strong>Mariano Dascanio<\/strong>, gerente de marketing de productos e inteligencia empresarial de la oficina local de Samsung, se\u00f1al\u00f3 que despu\u00e9s de un a\u00f1o de transici\u00f3n para la marca y con un escenario m\u00e1s definido para el 2025, creen que el mercado de <a href=\"https:\/\/www.iprofesional.com\/tecnologia\/410799-que-celulares-buenos-se-consiguen-por-menos-de-400-mil-pesos\" target=\"_blank\" title=\"Celulares buenos a menos de 400.000 pesos\" rel=\"noopener noreferrer\">celulares<\/a> se volver\u00e1 m\u00e1s competitivo gracias al ingreso de nuevos jugadores.\n<\/p>\n<p>&#8220;Esta competencia nos potencia a ser cada vez mejores en toda la <strong>cadena de comercializaci\u00f3n, distribuci\u00f3n y atenci\u00f3n al cliente <\/strong>y estamos convencidos de que el principal beneficiado va a ser el consumidor&#8221;, remarc\u00f3 Dascanio.\n<\/p>\n<p>Agreg\u00f3 que la aparici\u00f3n de nuevos competidores los exige a superarse en <strong>innovaci\u00f3n <\/strong>y desaf\u00eda a encontrar alternativas para que los consumidores elijan al mayor fabricante global de celulares.\n<\/p>\n<p>Dascanio revel\u00f3 que seg\u00fan <strong>GFK <\/strong>(consultora especializada en estudios de mercado con foco en electr\u00f3nica de consumo), m\u00e1s del 45% de los celulares vendidos en 2024 en la Argentina fueron de la marca Galaxy de Samsung, cifras seg\u00fan las cuales la firma lidera el mercado de smartphones. &#8220;Si consideramos ese mercado de smartphones en valores, la participaci\u00f3n de la marca Samsung asciende a 55%&#8221;, a\u00f1adi\u00f3.\n<\/p>\n<p>Desde la empresa de origen surcoreana se\u00f1alaron que el an\u00e1lisis de GFK se basa en las <strong>ventas realizadas por distribuidores oficiales de la marca a consumidores finales<\/strong>, y no a partir de la producci\u00f3n de celulares en Tierra del Fuego o importaciones directas.\n<\/p>\n<p>Respecto a otros \u00e1mbitos del negocio local de Samsung, el gerente remarc\u00f3 que contin\u00faan &#8220;liderando el segmento de <strong>inteligencia artificial <\/strong>en el mercado de los smartphones. Lo iniciamos con el S24 en enero y hoy est\u00e1 presente en todo nuestro portfolio &#8216;mobile'&#8221;.\n<\/p>\n<p>Un punto central de la estrategia de las marcas de tecnolog\u00eda de consumo para fidelizar a sus clientes radica en su ecosistema de productos que giran en torno al celular. &#8220;Acabamos de lanzar el (reloj) <strong>Watch <\/strong>7 y los (auriculares) Buds 3 y duplicamos nuestras estimaciones de venta. Este resultado nos confirma que hay un consumidor \u00e1vido de estos productos que ofrecen una experiencia multidipositivo&#8221;.\n<\/p>\n<p>Sobre los lanzamientos m\u00e1s recientes record\u00f3 que el 25 de octubre se anunci\u00f3 el <strong>Galaxy S24 Fe <\/strong>y para este lanzamiento volvieron ofrecerle al consumidor su paquete diferencial que incluye cuotas sin inter\u00e9s, v\u00e1uchers y plan canje.\n<\/p>\n<h2>Motorola apela a la historia<\/h2>\n<p><strong>Pablo Brancone<\/strong>, gerente de producto de Motorola Argentina, Uruguay, Paraguay y Bolivia, record\u00f3 que la empresa est\u00e1 en la Argentina desde hace m\u00e1s de 60 a\u00f1os y en el a\u00f1o 2000 decidi\u00f3 el inicio de la producci\u00f3n en Tierra del Fuego, antes que se implementara el r\u00e9gimen de producci\u00f3n.\n<\/p>\n<p>&#8220;Hoy producimos casi la totalidad de nuestro portafolio en la isla. Por la normativa, <strong>hoy conviene producir ac\u00e1<\/strong>. Este modelo lo tenemos muy asumido y sabemos c\u00f3mo funciona. Hemos optimizado el proceso productivo, para seguir llegando a los usuarios en las mejores condiciones de especificaciones y precio, siempre con el objetivo de democratizar la tecnolog\u00eda&#8221;, dijo Brancone.\n<\/p>\n<p>El ejecutivo remarc\u00f3 que Motorola se destaca por su adaptaci\u00f3n al cambio: &#8220;Por supuesto que si cambian las reglas nos adaptaremos. Somos la \u00fanica empresa que nunca se fue de la Argentina. <span>Otros se fueron y volvieron, otros se fueron y nunca volvieron y otros nunca entraron. <\/span>Nosotros hace 60 a\u00f1os que estamos ac\u00e1, pasamos las buenas y las malas. Tenemos en el ADN el adaptarnos&#8221;.\n<\/p>\n<p>Un dato llamativo de esta marca: <strong>la Argentina tiene la cuota de mercado de <a href=\"https:\/\/www.iprofesional.com\/tecnologia\/411690-que-celular-conviene-comprar-fuera-de-argentina\" target=\"_blank\" title=\"Celulares qu\u00e9 conviene comprar fuera de la Argentina\" rel=\"noopener noreferrer\">celulares<\/a> m\u00e1s alta de Motorola a nivel global<\/strong>. &#8220;Eso nos convierte en un mercado muy importante para la marca y por eso es un orgullo para nosotros ser hoy el l\u00edder del mercado: cerramos el segundo trimestre del a\u00f1o, que va de abril a junio, con casi 50% de &#8216;market share&#8217;, logrando la primera posici\u00f3n en el mercado local&#8221;, concluy\u00f3 Brancone.\n<\/p>\n<p>Dentro del portafolio de celulares de esta firma perteneciente al grupo chino Lenovo, el lanzamiento local m\u00e1s reciente tuvo como protagonista al <strong>Motorola Edge 50<\/strong>. Desde la empresa se\u00f1alaron que se trata de un dispositivo que mezcla est\u00e9tica con durabilidad en el dise\u00f1o para convertirse en el celular m\u00e1s delgado del mundo.\n<\/p>\n<p>Cuenta con <strong>certificaci\u00f3n militar MIL-810H e IP68 <\/strong>capaz de soportar altos niveles de humedad, funcionar en temperaturas altas y bajas y hasta 1,5 m de inmersi\u00f3n en agua dulce con un per\u00edodo de tiempo de 30 minutos.\n<\/p>\n<p>Este equipo presenta adem\u00e1s, un sistema de c\u00e1mara impulsado por <strong>Moto AI <\/strong>(la inteligencia artificial de la marca), sobre la cual prometen que permitir\u00e1 a los usuarios explorar su creatividad y obtener grandes resultados fotogr\u00e1ficos en diferentes escenarios o condiciones de iluminaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"\n<div class=\"media_block\"><img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/11\/samsung-y-motorola-revelan-sus-armas-contra-los-nuevos-competidores-chinos.jpg\"><\/div>\n<p> Los movimientos de los fabricantes chinos de celulares son seguidos de cerca por Samsung y Motorola, que ostentan m\u00e1s del 80% de las ventas en el pa\u00eds <iframe width=\"0\" height=\"0\" border=\"0\"> <script> (function(i,s,o,g,r,a,m){i['GoogleAnalyticsObject']=r;i[r]=i[r]||function(){ (i[r].q=i[r].q||[]).push(arguments)},i[r].l=1*new Date();a=s.createElement(o), m=s.getElementsByTagName(o)[0];a.async=1;a.src=g;m.parentNode.insertBefore(a,m) })(window,document,'script','https:\/\/www.google-analytics.com\/analytics.js','ga'); ga('create', 'GTM-5LW5KQD', 'auto'); ga('require', 'displayfeatures'); ga('set', 'campaignSource', 'RSS Client for iProfesional'); ga('set', 'campaignMedium', 'RSS Client for iProfesional'); ga('set', {\"dataSource\": \"rss.atom.iprofesional.com\"}); ga('set', {\"referrer\": \"rss.atom.iprofesional.com\"}); ga('set', 'title', 'RSS Client for iProfesional'); ga('send', 'pageview'); <\/script> <!-- Begin comScore Tag --> <script> var _comscore = _comscore || []; _comscore.push({ c1: \"2\", c2: \"16597048\" }); (function() { var s = document.createElement(\"script\"), el = document.getElementsByTagName(\"script\")[0]; s.async = true; s.src = \"https:\/\/sb.scorecardresearch.com\/cs\/16597048\/beacon.js\"; el.parentNode.insertBefore(s, el); })(); <\/script> <noscript> <img decoding=\"async\" src=\"http:\/\/latecordoba.com\/wp-content\/uploads\/2024\/11\/samsung-y-motorola-revelan-sus-armas-contra-los-nuevos-competidores-chinos.gif\"> <\/noscript> <!-- End comScore Tag --> <\/iframe> <iframe border=\"0px\" style=\"display: none\" width=0 height=0 src=\"https:\/\/www.iprofesional.com\/ga4.html?gtag_id=G-N13KWJP8BK&amp;title=Samsung y Motorola revelan sus armas contra los nuevos competidores chinos&amp;location=https:\/\/www.iprofesional.com\/tecnologia\/416793-celulares-samsung-y-motorola-ante-los-competidores-chinos&amp;referrer=rss.atom.iprofesional.com&amp;ci=RSS Client for iProfesional&amp;cs=RSS Client for iProfesional&amp;cm=RSS&amp;cn=RSS Client for iProfesional&amp;cc=RSS Client for iProfesional\"><\/iframe>  <\/p>\n","protected":false},"author":1,"featured_media":29099,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"_links":{"self":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/29098"}],"collection":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/comments?post=29098"}],"version-history":[{"count":0,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/posts\/29098\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media\/29099"}],"wp:attachment":[{"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/media?parent=29098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/categories?post=29098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latecordoba.com\/index.php\/wp-json\/wp\/v2\/tags?post=29098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}